{"id":9742,"date":"2011-02-13T19:14:46","date_gmt":"2011-02-13T18:14:46","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=9742"},"modified":"2011-02-13T19:14:46","modified_gmt":"2011-02-13T18:14:46","slug":"fomento-recicla-los-talgo-del-cantabrico-para-ganar-velocidad-y-usarlos-en-galicia-en-2012","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2011\/02\/fomento-recicla-los-talgo-del-cantabrico-para-ganar-velocidad-y-usarlos-en-galicia-en-2012\/","title":{"rendered":"Fomento recicla los Talgo del Cant\u00e1brico para ganar velocidad y usarlos en Galicia en 2012"},"content":{"rendered":"<p>Los trenes que conectan Madrid con Asturias, Cantabria y Pa\u00eds Vasco se adaptan en taller para convertirse en h\u00edbridos<\/p>\n<p>SELINA OTERO &#8211; VIGO<br \/>\n<strong>Los trenes h\u00edbridos que conectar\u00e1n en 2012 Galicia con Madrid, reduciendo el tiempo de viaje en dos horas y media, no ser\u00e1n unidades nuevas sino Talgos-130 adaptados.<\/strong> En la actualidad, estos trenes unen Madrid con Pamplona, Pa\u00eds Vasco, Cantabria y Asturias mediante el servicio Alvia. Renfe ha iniciado el proceso para convertir estas unidades en trenes m\u00e1s potentes y veloces, prepar\u00e1ndolas en taller e incorpor\u00e1ndole &#8220;cabezas el\u00e9ctricas&#8221; para que el pr\u00f3ximo a\u00f1o pueden cubrir definitivamente el trayecto Madrid- Galicia y Madrid-Murcia surcando tanto las zonas ya electrificadas (preparadas para alta velocidad) y las todav\u00eda convencionales, como es el tramo entre Ourense y Medina del Campo, por ejemplo.<\/p>\n<p>M\u00e1s informaci\u00f3n en <a href=\"http:\/\/www.farodevigo.es\/galicia\/2011\/02\/11\/fomento-recicla-talgo-cantabrico-ganar-velocidad-usarlos-galicia-2012\/517495.html\"><strong>farodevigo.es<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los trenes que conectan Madrid con Asturias, Cantabria y Pa\u00eds Vasco se adaptan en taller para convertirse en h\u00edbridos SELINA<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[37,4,6,19,42],"class_list":["post-9742","post","type-post","status-publish","format-standard","hentry","tag-espana","tag-funiculars-i-telecabines","tag-informacio-de-caracter-general","tag-infraestructures","tag-llarga-distancia-larga-distancia","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=9742"}],"version-history":[{"count":2,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9742\/revisions"}],"predecessor-version":[{"id":9744,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9742\/revisions\/9744"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=9742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=9742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=9742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}