{"id":9603,"date":"2011-01-29T11:44:27","date_gmt":"2011-01-29T10:44:27","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=9603"},"modified":"2011-01-31T11:52:48","modified_gmt":"2011-01-31T10:52:48","slug":"adif-invierte-mas-de-32-millones-de-euros-en-la-instalacion-de-catenaria-rigida-en-el-tunel-de-sabadell-barcelona","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2011\/01\/adif-invierte-mas-de-32-millones-de-euros-en-la-instalacion-de-catenaria-rigida-en-el-tunel-de-sabadell-barcelona\/","title":{"rendered":"Adif invierte m\u00e1s de 3,2 millones de euros en la instalaci\u00f3n de catenaria r\u00edgida en el t\u00fanel de Sabadell (Barcelona)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9475\" title=\"Adif01\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2011\/01\/Adif01.gif\" alt=\"\" width=\"83\" height=\"35\" \/>Mejora de la red convencional de Barcelona<br \/>\n<strong>\u2022 La licitaci\u00f3n de este contrato permitir\u00e1 una significativa mejora de las prestaciones y la eficacia del servicio ferroviario al prevenir incidencias<br \/>\n\u2022 La nueva catenaria mejora el servicio en los tramos con un elevado tr\u00e1fico, al requerir un menor mantenimiento, disponer de mayor capacidad el\u00e9ctrica, y ofrecer m\u00e1s durabilidad, robustez y resistencia<\/strong><\/p>\n<p>Barcelona, 28 de enero de 2011 (Adif).<br \/>\nAdif ha licitado el contrato de obras de montaje de las instalaciones de la catenaria r\u00edgida en el t\u00fanel de Sabadell por un importe de 3.265.622,7 euros. El proyecto consiste en la sustituci\u00f3n de la catenaria actual por otra a base de perfiles de aluminio en los que se aloja el hilo de contacto por el que se suministra electricidad a los trenes.<\/p>\n<p>Esta actuaci\u00f3n permitir\u00e1 instalar la catenaria r\u00edgida en el t\u00fanel ferroviario situado entre las estaciones de Terrassa y Sabadell Sur, entre los p.k. 340\/142 y 345\/536, correspondientes a la l\u00ednea de ancho convencional Zaragoza-Lleida-Barcelona. El tramo afectado tiene una longitud de 5,4 km de v\u00eda doble de los que 100 m se reservar\u00e1n para las transiciones.<!--more--><\/p>\n<p>Las obras tienen una gran complejidad t\u00e9cnica debido a la singularidad del t\u00fanel de Sabadell, que cuenta con una b\u00f3veda irregular, seg\u00fan tramos, con placas de hormig\u00f3n, vigas met\u00e1licas y b\u00f3vedas de mortero.<\/p>\n<p>En concreto, se sustituir\u00e1 la l\u00ednea a\u00e9rea de contacto actualmente instalada por una r\u00edgida y se adecuar\u00e1 la catenaria convencional en las futuras zonas de transici\u00f3n con la catenaria r\u00edgida. Tambi\u00e9n est\u00e1 previsto que se adapten las alimentaciones y conexiones a la catenaria r\u00edgida desde los seccionadores situados junto a la boca del t\u00fanel lado Barcelona. El proyecto contemplar\u00e1, igualmente, el montaje de cable de tierra en toda la instalaci\u00f3n.<\/p>\n<p>El material que se va a instalar cuenta con vanos de 7 m entre suspensiones y permitir\u00e1 una velocidad de paso de 125 km\/h. El hilo de contacto ser\u00e1 de 150 mm2 de secci\u00f3n. La altura m\u00ednima de \u00e9sta sobre el plano de rodadura ser\u00e1 de 4,6 m mientras que las barras del carril conductor a instalar ser\u00e1n de 14 m.<\/p>\n<p>En total se colocar\u00e1n1.585 conjuntos de suspensi\u00f3n, 11,6 km de hilo de contacto, cuatro transiciones y 11 km de cable de puesta a tierra.<\/p>\n<p>Hasta el momento Adif ha completado con \u00e9xito la instalaci\u00f3n de catenaria r\u00edgida en otros puntos de la red como en la estaci\u00f3n de Sants o en los t\u00faneles urbanos de Barcelona en los trayectos Sants-Passeig de Gr\u00e0cia-Clot Arag\u00f3; Sants-Pla\u00e7a de Catalunya-Arc de Triomf; Arc de Triomf-Clot Arag\u00f3; Arc de Triomf-Sant Andreu Arenal-Torre Bar\u00f3 y Passeig de Gr\u00e0cia-Estaci\u00f3 de Fran\u00e7a.<\/p>\n<p>La valoraci\u00f3n del funcionamiento de la nueva catenaria en estos trayectos es excelente, ya que desde su instalaci\u00f3n no se ha registrado ninguna incidencia imputable a la l\u00ednea a\u00e9rea de contacto, lo que representa una significativa mejora de las prestaciones y la eficacia del servicio.<\/p>\n<p>M\u00e1s fiabilidad y seguridad<br \/>\nLa catenaria r\u00edgida dota a las instalaciones de una elevada fiabilidad, que redunda en una mejora de la regularidad en unos \u00e1mbitos especialmente importantes para la explotaci\u00f3n ferroviaria como son los t\u00faneles urbanos.<\/p>\n<p>La nueva catenaria mejora de manera significativa la calidad del servicio en los tramos que registran un elevado tr\u00e1fico, al requerir un menor mantenimiento, disponer de una gran capacidad de transporte de electricidad y ofrecer m\u00e1s prestaciones de durabilidad, robustez y resistencia, adem\u00e1s de prevenir posibles incidencias.<\/p>\n<p>La instalaci\u00f3n de catenaria r\u00edgida se realiz\u00f3 por primera vez en la red convencional en los t\u00faneles de Barcelona, en una longitud total de 47,5 km, y supuso una inversi\u00f3n de 11,7 millones de euros.<\/p>\n<p>Esta inversi\u00f3n, que se inscribe en el plan global de inversiones que el Ministerio de Fomento y Adif est\u00e1 desarrollando para la mejora permanente de las infraestructuras e instalaciones de la red de cercan\u00edas de Barcelona, tiene car\u00e1cter de obra por cuenta del Estado y se realiza en el marco del Contrato Programa suscrito con Adif.<\/p>\n<p>El plazo de ejecuci\u00f3n de esta obra es de 8 meses y est\u00e1 previsto llevarla a cabo minimizando las afecciones al tr\u00e1fico ferroviario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mejora de la red convencional de Barcelona \u2022 La licitaci\u00f3n de este contrato permitir\u00e1 una significativa mejora de las prestaciones<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[35,43],"class_list":["post-9603","post","type-post","status-publish","format-standard","hentry","tag-barcelona","tag-estacions","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=9603"}],"version-history":[{"count":2,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9603\/revisions"}],"predecessor-version":[{"id":9605,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9603\/revisions\/9605"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=9603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=9603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=9603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}