{"id":9365,"date":"2010-12-20T21:20:52","date_gmt":"2010-12-20T20:20:52","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=9365"},"modified":"2010-12-20T21:20:52","modified_gmt":"2010-12-20T20:20:52","slug":"adif-invierte-58-me-en-la-modernizacion-de-los-sistemas-de-comunicaciones-en-la-red-de-cercanias-de-barcelona","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2010\/12\/adif-invierte-58-me-en-la-modernizacion-de-los-sistemas-de-comunicaciones-en-la-red-de-cercanias-de-barcelona\/","title":{"rendered":"Adif invierte 5,8 M\u20ac en la modernizaci\u00f3n de los sistemas de comunicaciones en la red de cercan\u00edas de Barcelona"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9356\" title=\"Adif01\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/12\/Adif019.gif\" alt=\"\" width=\"83\" height=\"35\" \/>En los tramos Terrassa-Manresa y Granollers Canovelles-Vic-Ripoll se instalar\u00e1 la red GSM-R<br \/>\n<strong>\u2022 Los nuevos sistemas contribuir\u00e1n a mejorar la capacidad y regularidad de las circulaciones, favorecer\u00e1n la reducci\u00f3n de\u00a0 incidencias e incrementar\u00e1n la fiabilidad y seguridad de la explotaci\u00f3n ferroviaria; lo que aumentar\u00e1 la calidad del servicio<\/strong><\/p>\n<p>Barcelona, 20 de diciembre de 2010 (Adif).<br \/>\nEl Consejo de Administraci\u00f3n de Adif ha aprobado en su reuni\u00f3n de hoy la adjudicaci\u00f3n de la tercera fase de las obras de modernizaci\u00f3n del sistema de comunicaciones en la red de cercan\u00edas de Barcelona, por importe de 5.846.032,9 euros. Los trabajos consistir\u00e1n, principalmente, en la instalaci\u00f3n de la red de comunicaciones m\u00f3viles ferroviarias GSM-R en los tramos Terrassa-Manresa y Granollers Canovelles-Vic-Ripoll.<\/p>\n<p>Esta actuaci\u00f3n complementa las dos primeras fases del proyecto, adjudicadas el pasado mes de septiembre por la Sociedad Estatal de Infraestructuras del Transporte Terrestre (SEITT) para la instalaci\u00f3n de este sistema en cerca de 400 kil\u00f3metros de la red de cercan\u00edas de Barcelona.<\/p>\n<p><!--more-->El GSM-R es un avanzado sistema de transmisi\u00f3n por radio que utiliza frecuencias exclusivas para el ferrocarril, lo que garantiza una mayor fiabilidad y funcionalidad de las comunicaciones. Este equipamiento de radio m\u00f3vil digital est\u00e1 desplegado en la red de alta velocidad espa\u00f1ola y ofrece unas elevadas prestaciones respecto a los actuales dispositivos de radiotelefon\u00eda.<\/p>\n<p>Su instalaci\u00f3n en la red de cercan\u00edas de Barcelona representar\u00e1 una significativa mejora en la capacidad y regularidad de las circulaciones ferroviarias, favorecer\u00e1 la reducci\u00f3n de las incidencias e incrementar\u00e1\u00a0 la seguridad de la explotaci\u00f3n ferroviaria, lo que redundar\u00e1 en un aumento de la calidad del servicio ofrecido a los clientes del ferrocarril.<\/p>\n<p>La implementaci\u00f3n de estos sistemas permitir\u00e1 obtener una mayor funcionalidad y fiabilidad de las comunicaciones, ofrecer una cobertura de radio de acuerdo a los niveles de potencia exigidos tanto en tiempo como en espacio, y disponer de equipos que cumplen con los est\u00e1ndares internacionales, contribuyendo as\u00ed a operar con un sistema de gesti\u00f3n m\u00e1s manejable y con nuevas prestaciones.<\/p>\n<p>Esta actuaci\u00f3n, que tiene car\u00e1cter de obra por cuenta del Estado y se realiza en el marco del Contrato Programa suscrito con Adif, se inscribe en el Plan de Cercan\u00edas de Barcelona 2008-2015 puesto en marcha por el Ministerio de Fomento para la mejora permanente de las infraestructuras y las estaciones de la citada red.<\/p>\n<p><strong>Actuaciones a desarrollar<\/strong><br \/>\nLa red GSM-R se instalar\u00e1 en los trayectos Terrassa-Manresa, en la l\u00ednea Barcelona-Manresa, y Granollers Canovelles-Vic-Ripoll, en la l\u00ednea Barcelona-Puigcerd\u00e0, que suman una longitud total superior a 100 kil\u00f3metros.<\/p>\n<p>Entre otras, las operaciones t\u00e9cnicas consistir\u00e1n en la instalaci\u00f3n de estaciones base transceptoras (BTS) y repetidores \u00f3pticos (FOR) en ambos trayectos, su integraci\u00f3n en los equipamientos de control y gesti\u00f3n existentes, la reutilizaci\u00f3n de la actual red de fibra \u00f3ptica como soporte f\u00edsico de la red de transmisi\u00f3n SDH, y el tendido de cableado el\u00e9ctrico de alimentaci\u00f3n y de fibra \u00f3ptica para dar servicio a los repetidores. Los trabajos ser\u00e1n ejecutados por la empresa Nokia Siemens Networks.<\/p>\n<p>Asimismo, se instalar\u00e1n nuevos nodos de comunicaciones y equipos rectificadores que se integrar\u00e1n en los sistemas de operaci\u00f3n y mantenimiento existentes y se llevar\u00e1n a cabo trabajos de acondicionamiento de dependencias t\u00e9cnicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los tramos Terrassa-Manresa y Granollers Canovelles-Vic-Ripoll se instalar\u00e1 la red GSM-R \u2022 Los nuevos sistemas contribuir\u00e1n a mejorar la<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[36,43,19,44],"class_list":["post-9365","post","type-post","status-publish","format-standard","hentry","tag-catalunya","tag-estacions","tag-infraestructures","tag-rodalies-cercanias","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=9365"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9365\/revisions"}],"predecessor-version":[{"id":9366,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9365\/revisions\/9366"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=9365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=9365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=9365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}