{"id":9333,"date":"2010-12-18T03:43:44","date_gmt":"2010-12-18T02:43:44","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=9333"},"modified":"2010-12-18T03:44:37","modified_gmt":"2010-12-18T02:44:37","slug":"adif-invertira-39-millones-de-euros-en-la-proteccion-acustica-del-tramo-sants-la-roca-del-valles-barcelona","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2010\/12\/adif-invertira-39-millones-de-euros-en-la-proteccion-acustica-del-tramo-sants-la-roca-del-valles-barcelona\/","title":{"rendered":"Adif invertir\u00e1 3,9 millones de euros en la protecci\u00f3n ac\u00fastica del tramo Sants-La Roca del Vall\u00e8s (Barcelona)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9335\" title=\"Adif01\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/12\/Adif016.gif\" alt=\"\" width=\"83\" height=\"35\" \/>L\u00ednea de Alta Velocidad Madrid-Barcelona-frontera francesa<br \/>\n<strong>\u2022 Se construir\u00e1n un total de 16 pantallas ac\u00fasticas, que suman una longitud superior a los 2,3 km <\/strong><\/p>\n<p>Barcelona, 15 de diciembre de 2010 (Adif).<br \/>\nAdif ha adjudicado las obras complementarias de protecci\u00f3n ac\u00fastica para el tramo Sants-La Roca del Vall\u00e8s (Barcelona) de la L\u00ednea de Alta Velocidad Madrid-Barcelona-frontera francesa. Los trabajos han sido adjudicados a la empresa Ferrovial Agroman con un presupuesto de 3.950.458,3 euros.<\/p>\n<p>Las obras consisten en la ejecuci\u00f3n de pantallas para minimizar el impacto ac\u00fastico en zonas industriales, residenciales y espacios rurales situados en el entorno de la infraestructura de alta velocidad en los tramos Mollet-Montorn\u00e8s y Montorn\u00e8s-La Roca.<\/p>\n<p>En esta actuaci\u00f3n se instalar\u00e1n 16 pantallas ac\u00fasticas, que suman una longitud total de 2.312,5 m y una superficie total de 9.391,5 m2, se ejecutar\u00e1n adosadas al trazado de la L\u00ednea de Alta Velocidad, ser\u00e1n de aluminio u hormig\u00f3n y tendr\u00e1n una altura variable de entre 3 y 5,5 m. Estar\u00e1n constituidas por m\u00f3dulos de diferentes dimensiones que se encajar\u00e1n entre s\u00ed por soportes conformados por perfiles met\u00e1licos anclados a la cimentaci\u00f3n. <!--more--><\/p>\n<p>Como elementos singulares, destacan la instalaci\u00f3n de 1.376,5 metros lineales de pantallas en zonas residenciales, entre las que figuran las urbanizaciones de Can Colet y Can Borrell, en el t\u00e9rmino municipal de La Roca del Vall\u00e8s, de 180 y 185,5 m de longitud respectivamente.<\/p>\n<p>La ejecuci\u00f3n de estas obras se inscribe en la misi\u00f3n de Adif de impulsar el sistema de transporte ferroviario espa\u00f1ol mediante el desarrollo y la gesti\u00f3n de un sistema de infraestructuras seguro, eficiente, sostenible desde el punto de vista socioecon\u00f3mico y medioambiental, con altos est\u00e1ndares de calidad y teniendo entre sus principales premisas el respeto al medio ambiente.<\/p>\n<p>En este sentido, se han realizado estudios previos en los que se ha analizado los niveles m\u00e1ximos de ruido generado por la explotaci\u00f3n de la infraestructura en diferentes puntos a lo largo del trazado, cuyos resultados han permitido definir la ubicaci\u00f3n de las pantallas para mitigar el impacto ac\u00fastico.<\/p>\n<p>Gracias a estas actuaciones, se reducir\u00e1n los niveles de inmisi\u00f3n sonora en el entorno de la nueva infraestructura y se mejorar\u00e1n las condiciones medioambientales en las zonas pr\u00f3ximas a la traza de la l\u00ednea de alta velocidad.<\/p>\n<p>El tramo Sants-La Roca del Vall\u00e8s de la L\u00ednea de Alta Velocidad Madrid-Barcelona-frontera francesa tiene una longitud de 34,3 kil\u00f3metros y discurre por los t\u00e9rminos municipales de Barcelona, Montcada i Reixac, La Llagosta, Mollet del Vall\u00e8s, Montmel\u00f3, Montorn\u00e8s del Vall\u00e8s, Vilanova del Vall\u00e8s y La Roca del Vall\u00e8s, en las comarcas del Barcelon\u00e8s, Vall\u00e8s Occidental y Vall\u00e8s Oriental.<\/p>\n<p>Fondos europeos<br \/>\nLa L\u00ednea de Alta Velocidad Madrid-Barcelona-frontera francesa, dentro del periodo 2000-2006, ha sido cofinanciada por el Fondo de Cohesi\u00f3n, en las obras de plataforma del tramo Madrid-Barcelona, as\u00ed como el suministro y montaje de v\u00eda del tramo Madrid-Vilafranca del Pened\u00e8s e instalaciones de electrificaci\u00f3n, se\u00f1alizaci\u00f3n y comunicaciones del tramo Madrid-Lleida, con una ayuda que asciende a 3.388,9 millones de euros.<\/p>\n<p>Las Ayudas RTE-T (Redes Transeuropeas de Transporte), en el mismo periodo han financiado los estudios y proyectos, as\u00ed como las obras de la plataforma del tramo Ma\u00e7anet-Sils, con una ayuda que asciende a 70,9 millones de euros.<\/p>\n<p>En el periodo 2007-2013 ser\u00e1n cofinanciadas por las ayudas RTE-T las obras de adecuaci\u00f3n para su explotaci\u00f3n en ancho internacional, del tramo Girona Mercanc\u00edas-Variante de Figueres, con una ayuda de 6,1 millones de euros. El Banco Europeo de Inversiones (BEI) tambi\u00e9n participa en la financiaci\u00f3n de este proyecto.<\/p>\n<p>El tramo Barcelona-Figueres de la L\u00ednea de Alta Velocidad Madrid-Barcelona-frontera francesa cuenta con una inversi\u00f3n aproximada de 4.200 millones de euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00ednea de Alta Velocidad Madrid-Barcelona-frontera francesa \u2022 Se construir\u00e1n un total de 16 pantallas ac\u00fasticas, que suman una longitud superior<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[41,36,19],"class_list":["post-9333","post","type-post","status-publish","format-standard","hentry","tag-ave","tag-catalunya","tag-infraestructures","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=9333"}],"version-history":[{"count":2,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9333\/revisions"}],"predecessor-version":[{"id":9337,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/9333\/revisions\/9337"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=9333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=9333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=9333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}