{"id":7757,"date":"2010-07-01T18:33:14","date_gmt":"2010-07-01T17:33:14","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=7757"},"modified":"2010-07-01T18:34:28","modified_gmt":"2010-07-01T17:34:28","slug":"adif-adjudica-la-asistencia-de-seguridad-y-salud-para-las-obras-de-la-estacion-de-la-sagrera-en-barcelona","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2010\/07\/adif-adjudica-la-asistencia-de-seguridad-y-salud-para-las-obras-de-la-estacion-de-la-sagrera-en-barcelona\/","title":{"rendered":"Adif adjudica la asistencia de seguridad y salud para las obras de la estaci\u00f3n de La Sagrera, en Barcelona"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7758\" title=\"Adif01\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/07\/Adif012.gif\" alt=\"\" width=\"83\" height=\"35\" \/>L\u00ednea de Alta Velocidad Madrid-Barcelona-frontera francesa<br \/>\n<strong>\u2022\u00a0\u00a0 \u00a0El contrato permite dotar de apoyo t\u00e9cnico a la direcci\u00f3n de obra para el control, vigilancia y seguimiento de los trabajos en materia de seguridad y salud<br \/>\n<\/strong><br \/>\nBarcelona, 1 de julio de 2010 (Adif).<\/p>\n<p>Adif ha adjudicado el contrato de asistencia para la coordinaci\u00f3n en materia de seguridad y salud de las obras de construcci\u00f3n de la estructura y accesos de la estaci\u00f3n de La Sagrera, en Barcelona.<\/p>\n<p>El presupuesto de este contrato asciende a 1.525.790,6 euros. La sociedad <a href=\"http:\/\/www.barcelonasagrera.com\/\">Barcelona Sagrera Alta Velocidad<\/a> cofinanciar\u00e1 esta actuaci\u00f3n aportando un total de 447.161,6 euros.<!--more--><\/p>\n<p>Esta adjudicaci\u00f3n permite dotar de apoyo t\u00e9cnico a la direcci\u00f3n de obra para el control, vigilancia y seguimiento de los trabajos en materia de seguridad y salud. La supervisi\u00f3n de las obras e instalaciones incluye todas las actuaciones necesarias para asegurar la correcta ejecuci\u00f3n de los trabajos, de acuerdo con lo establecido por los proyectos.<\/p>\n<p>Este contrato se suma a los previamente adjudicados para la construcci\u00f3n de la estructura y accesos de la estaci\u00f3n de La Sagrera, y que cuentan con una inversi\u00f3n de 589,2 millones de euros.<\/p>\n<p>La nueva estaci\u00f3n de La Sagrera se convertir\u00e1 en uno de los polos estrat\u00e9gicos para el desarrollo de la red de transporte p\u00fablico en el \u00e1rea metropolitana de Barcelona, estim\u00e1ndose que contar\u00e1 aproximadamente con 100 millones de usuarios anuales.<\/p>\n<p>Esta importante actuaci\u00f3n servir\u00e1 para conectar la alta velocidad ferroviaria con las redes de cercan\u00edas, regionales, metro, autob\u00fas y taxis, as\u00ed como con el transporte privado y representar\u00e1, igualmente, una gran operaci\u00f3n de transformaci\u00f3n urban\u00edstica de la zona en que se ubica, generando en su entorno nuevas oportunidades de desarrollo socioecon\u00f3mico.<\/p>\n<p>La empresa adjudicataria del contrato es <a href=\"http:\/\/www.cygsa.com\/\">Cygsa<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00ednea de Alta Velocidad Madrid-Barcelona-frontera francesa \u2022\u00a0\u00a0 \u00a0El contrato permite dotar de apoyo t\u00e9cnico a la direcci\u00f3n de obra para<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[41,35,19,2],"class_list":["post-7757","post","type-post","status-publish","format-standard","hentry","tag-ave","tag-barcelona","tag-infraestructures","tag-sant-andreu-districte","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/7757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=7757"}],"version-history":[{"count":3,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/7757\/revisions"}],"predecessor-version":[{"id":7760,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/7757\/revisions\/7760"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=7757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=7757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=7757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}