{"id":7670,"date":"2010-06-21T20:04:32","date_gmt":"2010-06-21T19:04:32","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=7670"},"modified":"2010-06-21T20:13:43","modified_gmt":"2010-06-21T19:13:43","slug":"inicio-de-las-obras-de-la-estacion-de-barcelona-la-sagrera-alta-velocidad","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2010\/06\/inicio-de-las-obras-de-la-estacion-de-barcelona-la-sagrera-alta-velocidad\/","title":{"rendered":"Inicio de las obras de la estaci\u00f3n de Barcelona-La Sagrera Alta Velocidad"},"content":{"rendered":"<p><strong><a href=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/06\/EU-Espa\u00f1a4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7675\" title=\"EU Espa\u00f1a\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/06\/EU-Espa\u00f1a4.jpg\" alt=\"\" width=\"79\" height=\"50\" \/><\/a><a href=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/06\/catalunya.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7676\" title=\"catalunya\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/06\/catalunya.jpg\" alt=\"\" width=\"79\" height=\"50\" \/><\/a><a href=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/06\/Barcelona.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7677\" title=\"Barcelona\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/06\/Barcelona.png\" alt=\"\" width=\"75\" height=\"50\" \/><\/a>\u201cNi Espanya, ni Catalunya, ni Barcelona no es poden permetre retardar m\u00e9s la connexi\u00f3 d\u2019alta velocitat amb Europa. Fa massa anys que esperem. Fa massa anys que afecta negativament la nostra competitivitat com a pa\u00eds\u201d. Ha estat l\u2019av\u00eds que ha llan\u00e7at aquesta tarda el president de la Generalitat, Jos\u00e9 Montilla, en l\u2019acte d\u2019inici d\u2019obres de la futura estaci\u00f3 intermodal de la Sagrera, a\u00a0 Barcelona, que ha de ser \u201cun pas m\u00e9s en un dels projectes m\u00e9s emblem\u00e0tics que s\u2019estan duent a terme en aquests moments a Catalunya i a Espanya\u201d.<br \/>\n<\/strong><br \/>\n\u201cPotser hi haur\u00e0 alguns projectes de l\u2019alta velocitat que s\u2019hauran de reprogramar a causa de les dificultats pressupost\u00e0ries. Aquest no\u201d, ha dit el cap del Govern, que tanmateix ha expressat el seu convenciment que el ministre de Foment, Jos\u00e9 Blanco, present en l\u2019acte, \u201cent\u00e9n que no podem permetre un nou ajornament d\u2019una infraestructura clau\u201d.<\/p>\n<p><strong>Comprom\u00eds per superar la crisi<\/strong><br \/>\nProjectes com el de la Sagrera, ha exposat el president, demostren el comprom\u00eds de les administracions central, auton\u00f2mica i local de seguir lluitant per superar la crisi. \u201cEns calen \u2013ha afegit- projectes, actituds i gestos\u201d com aquest per \u201ctrencar el cercle vici\u00f3s de crisi, des\u00e0nim i atur\u201d.<\/p>\n<p>En aquest context, el cap de l\u2019Executiu ha lamentat que, en canvi, hi ha \u201cqui sembla esfor\u00e7ar-se nom\u00e9s a trobar arguments perqu\u00e8 tot sembli m\u00e9s negatiu. I no els importa el des\u00e0nim col\u00b7lectiu o la irritaci\u00f3 social si aix\u00f2 millora les seves perspectives electorals. S\u00f3n especuladors de l\u2019\u00e0nim i la moral, tant o m\u00e9s perillosos que els especuladors financers\u201d.<\/p>\n<p>En contraposici\u00f3 amb aquestes actituds, el projecte de la Sagrera \u201c\u00e9s una acci\u00f3 ben real d\u2019obra p\u00fablica amb finan\u00e7ament comprom\u00e8s\u201d, fruit de la \u201ccooperaci\u00f3 entre administracions\u201d, ha dit.<\/p>\n<p>I ha concl\u00f2s: \u201cAquesta gran obra respondr\u00e0, tamb\u00e9, a la plena consci\u00e8ncia de la necessitat de ser austers, rigorosos, racionals\u201d, i, al mateix temps, \u201ca l\u2019ambici\u00f3 ben leg\u00edtima d\u2019una ciutat que afirma la seva voluntat de tenir un lloc indiscutit entre les ciutats m\u00e9s potents d\u2019Europa\u201d.<!--more--><\/p>\n<p>Blanco y Montilla asisten al acto de inicio de las obras de la nueva estaci\u00f3n de La Sagrera (Barcelona)<\/p>\n<p><strong>Cuenta con una inversi\u00f3n de 589 millones de euros<\/strong><\/p>\n<p>* La Sagrera se construir\u00e1 con criterios de eficiencia energ\u00e9tica y sostenibilidad, y ser\u00e1 completamente accesible a personas con discapacidad.<br \/>\n* Con una afluencia estimada de 100 millones de usuarios anuales, la estaci\u00f3n se convertir\u00e1 en un polo estrat\u00e9gico de la red de transporte p\u00fablico en el \u00e1rea metropolitana de Barcelona.<br \/>\n* Se trata del proyecto de soterramiento ferroviario m\u00e1s importante de Europa en la actualidad, con 38 hect\u00e1reas de superficie.<\/p>\n<p>lunes, 21 de junio de 2010<\/p>\n<p>El ministro de Fomento, Jos\u00e9 Blanco, el presidente de la Generalitat de Catalu\u00f1a, Jos\u00e9 Montilla, y el alcalde de Barcelona, Jordi Hereu, han presidido hoy en Barcelona al acto de inicio de las obras de construcci\u00f3n de la Estaci\u00f3n de La Sagrera.<\/p>\n<p>Al acto tambi\u00e9n han asistido el delegado del Gobierno en Catalu\u00f1a, Joan Rangel, el conseller de Pol\u00edtica Territorial y Obras P\u00fablicas, Joaquim Nadal, y el presidente de Adif, Antonio Gonz\u00e1lez Mar\u00edn.<\/p>\n<p>Se trata del proyecto ferroviario singular de mayor envergadura adjudicado en Espa\u00f1a, gracias a una inversi\u00f3n superior a 589,2 millones, y el proyecto de soterramiento ferroviario m\u00e1s grande de Europa en la actualidad, con 38 hect\u00e1reas de superficie.<\/p>\n<p>La nueva estaci\u00f3n central de La Sagrera se convertir\u00e1 en un nudo estrat\u00e9gico de la red de transporte p\u00fablico en el \u00e1rea metropolitana de Barcelona al conectar la ciudad de una forma m\u00e1s r\u00e1pida y segura con la red ferroviaria espa\u00f1ola y europea.<\/p>\n<p>Las instalaciones se han proyectado con capacidad para acoger un tr\u00e1nsito superior a los 100 millones de viajeros anuales, convirti\u00e9ndose en un intercambiador de primer orden, enlazando la alta velocidad ferroviaria con las redes de cercan\u00edas, regionales, metro, autob\u00fas y taxis, as\u00ed como con el transporte privado al estar conectada directamente con las principales v\u00edas de comunicaci\u00f3n.<\/p>\n<p>El conjunto de infraestructuras, la estaci\u00f3n central y la urbanizaci\u00f3n de los sectores de Sant Andreu y La Sagrera representan el proyecto de mayor inversi\u00f3n econ\u00f3mica a desarrollar en la ciudad de Barcelona en los pr\u00f3ximos a\u00f1os. La inversi\u00f3n global asciende a unos 2.250 millones de euros, sin contar con las posteriores actuaciones de urbanizaci\u00f3n y edificaciones de viviendas, equipamientos, comercios, oficinas y hoteles.<\/p>\n<p>En esta actuaci\u00f3n se cubrir\u00e1n 38 hect\u00e1reas de superficie ferroviaria, lo que permitir\u00e1 integrar los barrios separados por las v\u00edas, a lo largo de casi 4 kil\u00f3metros, entre la calle Espronceda y el Nus de la Trinitat, lo que supone una profunda transformaci\u00f3n urban\u00edstica y de vertebraci\u00f3n del territorio en 164 hect\u00e1reas, generando nuevas oportunidades de desarrollo econ\u00f3mico y de cohesi\u00f3n social.<br \/>\nPrincipales beneficios<br \/>\n<strong><br \/>\nLa construcci\u00f3n de La Sagrera ofrece como principales ventajas<\/strong>:<br \/>\n* Una nueva estaci\u00f3n que integrar\u00e1 en un mismo edificio, en dos niveles diferentes, los tr\u00e1ficos de cercan\u00edas y regionales por v\u00eda convencional, y los de alta velocidad y larga distancia en ancho internacional.<br \/>\n* Creaci\u00f3n de un espacio intermodal que conectar\u00e1 la alta velocidad con cercan\u00edas, regionales, metro y autobuses urbanos e interurbanos.<br \/>\n* Implantaci\u00f3n de criterios de accesibilidad integral para personas con discapacidad, criterios de eficiencia energ\u00e9tica y sostenibilidad para conseguir un uso racional de la energ\u00eda y un consumo responsable de los recursos naturales.<br \/>\n* Configuraci\u00f3n de un nuevo espacio urbano sobre los terrenos que libera toda la actuaci\u00f3n ferroviaria, mediante la construcci\u00f3n de una nueva estaci\u00f3n de varios niveles.<br \/>\n* Mejora de las condiciones de acceso al modo de transporte ferroviario en la ciudad de Barcelona.<br \/>\n* Nuevos accesos ferroviarios y viarios en los \u00e1mbitos urbanos de La Sagrera, Sant Andreu y Sant Mart\u00ed.<br \/>\n* Aumento de la seguridad con la adecuaci\u00f3n del esquema de v\u00edas para tecnolog\u00edas punta en sistemas de conducci\u00f3n autom\u00e1tica de trenes.<br \/>\n* Incremento de la capacidad y la regularidad, como resultado de disponer de doble v\u00eda en todo el trayecto.<br \/>\n* Aumento del confort, al establecerse unas condiciones \u00f3ptimas de rodadura y trazado.<br \/>\n* Reducci\u00f3n de tiempos de viaje y un aumento de la frecuencia de servicios, al disponer de v\u00edas espec\u00edficas para la log\u00edstica y el estacionamiento de trenes.<\/p>\n<p><strong>Caracter\u00edsticas de la nueva estaci\u00f3n<\/strong><br \/>\nLa nueva estaci\u00f3n ser\u00e1 semisoterrada y tendr\u00e1 una superficie de casi 259.000 m2, distribuidos en varios niveles y concentrando el m\u00e1ximo de servicios en vertical, contribuyendo a mejorar la eficacia en el movimiento de las personas. Su disposici\u00f3n dar\u00e1 continuidad al espacio p\u00fablico generado sobre las v\u00edas actuales y tendr\u00e1 dos accesos unidos por un gran espacio de conexiones.<\/p>\n<p>Los niveles superiores, a los que se acceder\u00e1 desde La Sagrera, corresponden a los servicios de alta velocidad y a la estaci\u00f3n de autobuses interurbanos. El vest\u00edbulo dispondr\u00e1 de un gran espacio central de acogida y distribuci\u00f3n de usuarios, taquillas y zona comercial. Para los servicios de alta velocidad se construir\u00e1n 10 v\u00edas, dos generales y ocho de servicio, con cuatro andenes de 400 m de longitud y un quinto de 200 m, todos ellos con un ancho de 12 m.<\/p>\n<p>Los niveles inferiores se destinar\u00e1n a los servicios de cercan\u00edas, metro y aparcamientos. Las v\u00edas de ancho convencional ser\u00e1n objeto de una profunda remodelaci\u00f3n para adecuar su paso por la futura estaci\u00f3n y se abrir\u00e1n en un haz de ocho v\u00edas al paso por la estaci\u00f3n con 4 andenes de 240 m de longitud. Despu\u00e9s del \u00e1mbito de la estaci\u00f3n, se ha proyectado un \u00e1rea log\u00edstica de servicios de ancho internacional para estacionamiento y mantenimiento.<\/p>\n<p>A ambos lados del vest\u00edbulo de cercan\u00edas se integrar\u00e1n 4 grandes aparcamientos, con una capacidad aproximada de 2.500 veh\u00edculos, para servicio tanto de la estaci\u00f3n ferroviaria como de la autobuses y en un futuro de la zona de servicios que se construir\u00e1 en el entorno. Las dos zonas de la estaci\u00f3n, lados La Sagrera y Sant Mart\u00ed, quedar\u00e1n unidas por un gran patio de conexiones que conforma el nudo intermodal entre los diferentes servicios de transporte p\u00fablico.<\/p>\n<p>La estructura se ha proyectado de forma que se garantiza la accesibilidad universal y el tr\u00e1nsito por todos los espacios del edificio. Asimismo, se han tenido en cuenta par\u00e1metros de ahorro de energ\u00eda y aislamiento t\u00e9rmico, de tal forma que se consigue un uso racional y eficiente de la energ\u00eda necesaria para la sostenibilidad y la adecuada utilizaci\u00f3n del edificio.<\/p>\n<p>Por su parte, las obras de construcci\u00f3n de los accesos, tanto ferroviarios como viarios as\u00ed como de parte de la estructura de la estaci\u00f3n de autobuses, comprenden el \u00e1mbito situado entre el Pont de Bac de Roda hasta la futura estaci\u00f3n, con una longitud de 220 m, y desde este punto hasta el denominado tri\u00e1ngulo ferroviario.<\/p>\n<p>La accesibilidad de veh\u00edculos se resolver\u00e1 mediante la red viaria en superficie prevista para el sector, completada con un sistema de viarios segregados que permiten el acceso a los aparcamientos, la estaci\u00f3n de autobuses y las zonas de log\u00edstica de la futura estaci\u00f3n.<\/p>\n<p>El inicio de las obras de construcci\u00f3n de la nueva estaci\u00f3n central de La Sagrera reafirma la apuesta del Gobierno de Espa\u00f1a por la potenciaci\u00f3n del ferrocarril como uno de los principales medios de transporte, motor del desarrollo urban\u00edstico y econ\u00f3mico de las ciudades, generador de empleo y capaz de favorecer la cohesi\u00f3n social. Esta apuesta se traduce en el desarrollo de nuevas infraestructuras, como la L\u00ednea de Alta Velocidad Madrid-Barcelona-frontera francesa, y la modernizaci\u00f3n e impulso de la red ferroviaria de Catalu\u00f1a.<\/p>\n<p><strong>Cuenta con una inversi\u00f3n de 589 millones de euros<\/strong><br \/>\nBlanco y Montilla asisten al acto de inicio de las obras de la nueva estaci\u00f3n de La Sagrera (Barcelona)<\/p>\n<p>Se trata del proyecto de soterramiento ferroviario m\u00e1s importante de Europa en la actualidad, con 38 hect\u00e1reas de superficie ? Con una afluencia estimada de 100 millones de usuarios anuales, la estaci\u00f3n se convertir\u00e1 en un polo estrat\u00e9gico de la red de transporte p\u00fablico en el \u00e1rea metropolitana de Barcelona ? La Sagrera se construir\u00e1 con criterios de eficiencia energ\u00e9tica y sostenibilidad, y ser\u00e1 completamente accesible a personas con discapacidad<\/p>\n<p>Foto de la noticia21\/06\/2010. &#8211; El ministro de Fomento, Jos\u00e9 Blanco, el presidente de la Generalitat de Catalu\u00f1a, Jos\u00e9 Montilla, y el alcalde de Barcelona, Jordi Hereu, han presidido hoy en Barcelona al acto de inicio de las obras de construcci\u00f3n de la Estaci\u00f3n de La Sagrera.<\/p>\n<p>Al acto tambi\u00e9n han asistido el delegado del Gobierno en Catalu\u00f1a, Joan Rangel, el conseller de Pol\u00edtica Territorial y Obras P\u00fablicas, Joaquim Nadal, y el presidente de Adif, Antonio Gonz\u00e1lez Mar\u00edn.<\/p>\n<p>Se trata del proyecto ferroviario singular de mayor envergadura adjudicado en Espa\u00f1a, gracias a una inversi\u00f3n superior a 589,2 millones, y el proyecto de soterramiento ferroviario m\u00e1s grande de Europa en la actualidad, con 38 hect\u00e1reas de superficie.<\/p>\n<p>La nueva estaci\u00f3n central de La Sagrera se convertir\u00e1 en un nudo estrat\u00e9gico de la red de transporte p\u00fablico en el \u00e1rea metropolitana de Barcelona al conectar la ciudad de una forma m\u00e1s r\u00e1pida y segura con la red ferroviaria espa\u00f1ola y europea.<\/p>\n<p>Las instalaciones se han proyectado con capacidad para acoger un tr\u00e1nsito superior a los 100 millones de viajeros anuales, convirti\u00e9ndose en un intercambiador de primer orden, enlazando la alta velocidad ferroviaria con las redes de cercan\u00edas, regionales, metro, autob\u00fas y taxis, as\u00ed como con el transporte privado al estar conectada directamente con las principales v\u00edas de comunicaci\u00f3n.<\/p>\n<p>El conjunto de infraestructuras, la estaci\u00f3n central y la urbanizaci\u00f3n de los sectores de Sant Andreu y La Sagrera representan el proyecto de mayor inversi\u00f3n econ\u00f3mica a desarrollar en la ciudad de Barcelona en los pr\u00f3ximos a\u00f1os. La inversi\u00f3n global asciende a unos 2.250 millones de euros, sin contar con las posteriores actuaciones de urbanizaci\u00f3n y edificaciones de viviendas, equipamientos, comercios, oficinas y hoteles.<\/p>\n<p>En esta actuaci\u00f3n se cubrir\u00e1n 38 hect\u00e1reas de superficie ferroviaria, lo que permitir\u00e1 integrar los barrios separados por las v\u00edas, a lo largo de casi 4 kil\u00f3metros, entre la calle Espronceda y el Nus de la Trinitat, lo que supone una profunda transformaci\u00f3n urban\u00edstica y de vertebraci\u00f3n del territorio en 164 hect\u00e1reas, generando nuevas oportunidades de desarrollo econ\u00f3mico y de cohesi\u00f3n social.<\/p>\n<p><strong>Principales beneficios<\/strong><br \/>\nLa construcci\u00f3n de La Sagrera ofrece como principales ventajas:<\/p>\n<p>\u2022 Una nueva estaci\u00f3n que integrar\u00e1 en un mismo edificio, en dos niveles diferentes, los tr\u00e1ficos de cercan\u00edas y regionales por v\u00eda convencional, y los de alta velocidad y larga distancia en ancho internacional.<\/p>\n<p>\u2022 Creaci\u00f3n de un espacio intermodal que conectar\u00e1 la alta velocidad con cercan\u00edas, regionales, metro y autobuses urbanos e interurbanos.<\/p>\n<p>\u2022 Implantaci\u00f3n de criterios de accesibilidad integral para personas con discapacidad, criterios de eficiencia energ\u00e9tica y sostenibilidad para conseguir un uso racional de la energ\u00eda y un consumo responsable de los recursos naturales.<\/p>\n<p>\u2022 Configuraci\u00f3n de un nuevo espacio urbano sobre los terrenos que libera toda la actuaci\u00f3n ferroviaria, mediante la construcci\u00f3n de una nueva estaci\u00f3n de varios niveles.<\/p>\n<p>\u2022 Mejora de las condiciones de acceso al modo de transporte ferroviario en la ciudad de Barcelona.<\/p>\n<p>\u2022 Nuevos accesos ferroviarios y viarios en los \u00e1mbitos urbanos de La Sagrera, Sant Andreu y Sant Mart\u00ed.<\/p>\n<p>\u2022 Aumento de la seguridad con la adecuaci\u00f3n del esquema de v\u00edas para tecnolog\u00edas punta en sistemas de conducci\u00f3n autom\u00e1tica de trenes.<\/p>\n<p>\u2022 Incremento de la capacidad y la regularidad, como resultado de disponer de doble v\u00eda en todo el trayecto.<\/p>\n<p>\u2022 Aumento del confort, al establecerse unas condiciones \u00f3ptimas de rodadura y trazado.<\/p>\n<p>\u2022 Reducci\u00f3n de tiempos de viaje y un aumento de la frecuencia de servicios, al disponer de v\u00edas espec\u00edficas para la log\u00edstica y el estacionamiento de trenes.<\/p>\n<p><strong>Caracter\u00edsticas de la nueva estaci\u00f3n<\/strong><br \/>\nLa nueva estaci\u00f3n ser\u00e1 semisoterrada y tendr\u00e1 una superficie de casi 259.000 m2, distribuidos en varios niveles y concentrando el m\u00e1ximo de servicios en vertical, contribuyendo a mejorar la eficacia en el movimiento de las personas. Su disposici\u00f3n dar\u00e1 continuidad al espacio p\u00fablico generado sobre las v\u00edas actuales y tendr\u00e1 dos accesos unidos por un gran espacio de conexiones.<\/p>\n<p>Los niveles superiores, a los que se acceder\u00e1 desde La Sagrera, corresponden a los servicios de alta velocidad y a la estaci\u00f3n de autobuses interurbanos. El vest\u00edbulo dispondr\u00e1 de un gran espacio central de acogida y distribuci\u00f3n de usuarios, taquillas y zona comercial. Para los servicios de alta velocidad se construir\u00e1n 10 v\u00edas, dos generales y ocho de servicio, con cuatro andenes de 400 m de longitud y un quinto de 200 m, todos ellos con un ancho de 12 m.<\/p>\n<p>Los niveles inferiores se destinar\u00e1n a los servicios de cercan\u00edas, metro y aparcamientos. Las v\u00edas de ancho convencional ser\u00e1n objeto de una profunda remodelaci\u00f3n para adecuar su paso por la futura estaci\u00f3n y se abrir\u00e1n en un haz de ocho v\u00edas al paso por la estaci\u00f3n con 4 andenes de 240 m de longitud. Despu\u00e9s del \u00e1mbito de la estaci\u00f3n, se ha proyectado un \u00e1rea log\u00edstica de servicios de ancho internacional para estacionamiento y mantenimiento.<\/p>\n<p>A ambos lados del vest\u00edbulo de cercan\u00edas se integrar\u00e1n 4 grandes aparcamientos, con una capacidad aproximada de 2.500 veh\u00edculos, para servicio tanto de la estaci\u00f3n ferroviaria como de la autobuses y en un futuro de la zona de servicios que se construir\u00e1 en el entorno. Las dos zonas de la estaci\u00f3n, lados La Sagrera y Sant Mart\u00ed, quedar\u00e1n unidas por un gran patio de conexiones que conforma el nudo intermodal entre los diferentes servicios de transporte p\u00fablico.<\/p>\n<p>La estructura se ha proyectado de forma que se garantiza la accesibilidad universal y el tr\u00e1nsito por todos los espacios del edificio. Asimismo, se han tenido en cuenta par\u00e1metros de ahorro de energ\u00eda y aislamiento t\u00e9rmico, de tal forma que se consigue un uso racional y eficiente de la energ\u00eda necesaria para la sostenibilidad y la adecuada utilizaci\u00f3n del edificio.<\/p>\n<p>Por su parte, las obras de construcci\u00f3n de los accesos, tanto ferroviarios como viarios as\u00ed como de parte de la estructura de la estaci\u00f3n de autobuses, comprenden el \u00e1mbito situado entre el Pont de Bac de Roda hasta la futura estaci\u00f3n, con una longitud de 220 m, y desde este punto hasta el denominado tri\u00e1ngulo ferroviario.<\/p>\n<p>La accesibilidad de veh\u00edculos se resolver\u00e1 mediante la red viaria en superficie prevista para el sector, completada con un sistema de viarios segregados que permiten el acceso a los aparcamientos, la estaci\u00f3n de autobuses y las zonas de log\u00edstica de la futura estaci\u00f3n.<\/p>\n<p>El inicio de las obras de construcci\u00f3n de la nueva estaci\u00f3n central de La Sagrera reafirma la apuesta del Gobierno de Espa\u00f1a por la potenciaci\u00f3n del ferrocarril como uno de los principales medios de transporte, motor del desarrollo urban\u00edstico y econ\u00f3mico de las ciudades, generador de empleo y capaz de favorecer la cohesi\u00f3n social. Esta apuesta se traduce en el desarrollo de nuevas infraestructuras, como la L\u00ednea de Alta Velocidad Madrid-Barcelona-frontera francesa, y la modernizaci\u00f3n e impulso de la red ferroviaria de Catalu\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNi Espanya, ni Catalunya, ni Barcelona no es poden permetre retardar m\u00e9s la connexi\u00f3 d\u2019alta velocitat amb Europa. Fa massa<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[41,35,4,19,2],"class_list":["post-7670","post","type-post","status-publish","format-standard","hentry","tag-ave","tag-barcelona","tag-funiculars-i-telecabines","tag-infraestructures","tag-sant-andreu-districte","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/7670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=7670"}],"version-history":[{"count":3,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/7670\/revisions"}],"predecessor-version":[{"id":7674,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/7670\/revisions\/7674"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=7670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=7670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=7670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}