{"id":6604,"date":"2010-03-12T13:11:02","date_gmt":"2010-03-12T12:11:02","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=6604"},"modified":"2010-03-15T13:14:54","modified_gmt":"2010-03-15T12:14:54","slug":"adif-inicia-la-colocacion-de-las-vigas-estructurales-de-la-nueva-estacion-de-cercanias-de-sagrera-meridiana","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2010\/03\/adif-inicia-la-colocacion-de-las-vigas-estructurales-de-la-nueva-estacion-de-cercanias-de-sagrera-meridiana\/","title":{"rendered":"Adif inicia la colocaci\u00f3n de las vigas estructurales de la nueva estaci\u00f3n de Cercan\u00edas de Sagrera-Meridiana"},"content":{"rendered":"<p><a href=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/03\/Renfe0213.gif\"><a href=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/03\/Adif015.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-6609\" title=\"Adif01\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/03\/Adif015.gif\" alt=\"\" width=\"100\" height=\"42\" \/><\/a><\/a>Obras de mejora en la red convencional de Catalunya<br \/>\n<strong>\u2022 Los trabajos se desarrollar\u00e1n a lo largo de este fin de semana, entre las 8.00 horas del s\u00e1bado y las 15.00 horas del domingo \u2022 El tr\u00e1fico de entrada a Barcelona por la avenida Meridiana se desviar\u00e1 por la calle Concepci\u00f3n Arenal \u2022<\/strong> La nueva estaci\u00f3n de Sagrera-Meridiana, que supondr\u00e1 una inversi\u00f3n de m\u00e1s de 34 millones de euros, ser\u00e1 uno de los ejes principales del transporte p\u00fablico en el \u00e1rea metropolitana de la Ciudad Condal<\/p>\n<p><a href=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/03\/Plano-Sagrera-Meridiana.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6605\" title=\"Plano Sagrera-Meridiana\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/03\/Plano-Sagrera-Meridiana.jpg\" alt=\"\" width=\"405\" height=\"286\" srcset=\"https:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/03\/Plano-Sagrera-Meridiana.jpg 405w, https:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/03\/Plano-Sagrera-Meridiana-300x211.jpg 300w\" sizes=\"auto, (max-width: 405px) 100vw, 405px\" \/><\/a>11\/03\/2010. &#8211; Adif iniciar\u00e1 este fin de semana el proceso de colocaci\u00f3n de las vigas prefabricadas que formar\u00e1n parte de la cubrici\u00f3n de la estructura de pilotes y micropilotes que se ha ejecutado con motivo de la construcci\u00f3n de la nueva estaci\u00f3n de cercan\u00edas de Sagrera-Meridiana. Como consecuencia de estos trabajos, el Ayuntamiento y Adif establecer\u00e1n un itinerario alternativo para los veh\u00edculos que circulen por los carriles de entrada de la avenida Meridiana, en el tramo comprendido entre Olesa y Cardenal Tedeschini.<!--more--><\/p>\n<p>La nueva estaci\u00f3n de cercan\u00edas de Sagrera-Meridiana, cuyas obras cuentan con un presupuesto de adjudicaci\u00f3n de 34.321.667 euros, ser\u00e1 uno de los polos estrat\u00e9gicos de la red de transporte p\u00fablico en el \u00e1rea metropolitana de Barcelona, ya que dar\u00e1 servicio a las l\u00edneas R3, R4 y R7 de la red de cercan\u00edas de Barcelona y al Metro. Su construcci\u00f3n se enmarca en el acuerdo firmado el 17 de mayo de 2007 entre el Ministerio de Fomento y la Generalitat para la realizaci\u00f3n de obras de mejora de la red de ancho convencional en Catalu\u00f1a.<\/p>\n<p>Para colocar las 32 vigas de 14 metros de longitud, 1,05 m de alto y 0,60 m de ancho, que cubrir\u00e1n las rampas de acceso a la nueva instalaci\u00f3n, se trabajar\u00e1 durante las 24 horas, de modo que la circulaci\u00f3n de veh\u00edculos por esta zona se restablezca el d\u00eda 14 a las 15.00 horas.<\/p>\n<p>Para ello se utilizar\u00e1n dos gr\u00faas de grandes dimensiones a las que se sumar\u00e1 una tercera, de reserva, por si fuera necesaria. Las gr\u00faas se ubicar\u00e1n en el lado monta\u00f1a de la calzada mientras que los camiones se situar\u00e1n en la avenida Meridiana a partir de la calle Pintor Alzamora.<\/p>\n<p>Esta es la primera fase del proceso de cubrici\u00f3n, que continuar\u00e1 a partir del 29 de marzo.<\/p>\n<p>Afectaciones al tr\u00e1fico<\/p>\n<p>Como consecuencia de este proceso y con el fin de garantizar la seguridad, el Ayuntamiento de Barcelona y Adif han dise\u00f1ado un plan de circulaci\u00f3n alternativo a los carriles de entrada a la Ciudad Condal por la avenida Meridiana. As\u00ed, se ha establecido un itinerario de acceso por la calle Concepci\u00f3n Arenal que estar\u00e1 debidamente se\u00f1alizado para que el tr\u00e1fico rodado sea lo m\u00e1s fluido posible. A la altura de las calles Espronceda y Navas de Tolosa, los veh\u00edculos podr\u00e1n retomar la avenida Meridiana. En lo que se refiere a la salida de Barcelona por esta v\u00eda, la circulaci\u00f3n no se ver\u00e1 afectada.<\/p>\n<p>El corte de circulaci\u00f3n empezar\u00e1 el s\u00e1bado a las 8.00 horas y finalizar\u00e1 el domingo a las 15.00 horas. Durante este tiempo, las l\u00edneas B-22 y 62 de TMB desviar\u00e1n su ruta por los itinerarios alternativos establecidos. Los vecinos, sin embargo, tendr\u00e1n en todo momento acceso a las plazas de aparcamiento que se encuentran en la zona afectada.<\/p>\n<p>Para m\u00e1s informaci\u00f3n, los vecinos pueden dirigirse al punto de informaci\u00f3n y atenci\u00f3n al ciudadano de Adif, situado en la calle Baixada de la Sagrera, 2; al tel\u00e9fono 93 445 30 22 o al correo electr\u00f3nico: piac.bcn@adif.es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obras de mejora en la red convencional de Catalunya \u2022 Los trabajos se desarrollar\u00e1n a lo largo de este fin<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[17,19,2],"class_list":["post-6604","post","type-post","status-publish","format-standard","hentry","tag-afectacions-e-incidencies","tag-infraestructures","tag-sant-andreu-districte","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/6604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=6604"}],"version-history":[{"count":3,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/6604\/revisions"}],"predecessor-version":[{"id":6610,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/6604\/revisions\/6610"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=6604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=6604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=6604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}