{"id":39124,"date":"2025-01-15T18:26:17","date_gmt":"2025-01-15T17:26:17","guid":{"rendered":"https:\/\/www.agrupament.cat\/portal\/?p=39124"},"modified":"2025-01-15T18:26:17","modified_gmt":"2025-01-15T17:26:17","slug":"las-obras-entre-tarragona-y-sant-vicenc-de-calders-alcanzan-el-70-de-ejecucion","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2025\/01\/las-obras-entre-tarragona-y-sant-vicenc-de-calders-alcanzan-el-70-de-ejecucion\/","title":{"rendered":"Las obras entre Tarragona y Sant Vicen\u00e7 de Calders alcanzan el 70% de ejecuci\u00f3n"},"content":{"rendered":"<p>Actuaci\u00f3n esencial para el desarrollo del Corredor Mediterr\u00e1neo en Catalunya<br \/>\n<strong>\u00b7 Se mantiene la planificaci\u00f3n prevista para restablecer el tr\u00e1fico ferroviario en el mes de marzo <\/strong><br \/>\n<strong>\u00b7 El ejercicio de 2024 se cerr\u00f3 con una inversi\u00f3n hist\u00f3rica en el Corredor Mediterr\u00e1neo, ya que el valor global de las obras ejecutadas ascendi\u00f3 a 1.280 millones de euros<\/strong><\/p>\n<p>15 enero 2025<br \/>\nAdif ya ha ejecutado aproximadamente el 70% de las obras de la fase principal de la adaptaci\u00f3n al ancho internacional del tramo Tarragona-Sant Vicen\u00e7 de Calders, una actuaci\u00f3n esencial y la de mayor importancia estrat\u00e9gica que se est\u00e1 ejecutando actualmente para el desarrollo del Corredor Mediterr\u00e1neo en Catalunya.<\/p>\n<p>La adecuaci\u00f3n de la estructura del t\u00fanel de Roda de Ber\u00e0, y la adaptaci\u00f3n de este tramo al ancho internacional mediante la posterior instalaci\u00f3n del tercer carril, garantizar\u00e1 la conexi\u00f3n de la gran \u00e1rea socioecon\u00f3mica, industrial y productiva de Tarragona con el norte de Catalunya y el resto de Europa. Se completar\u00e1 as\u00ed el eje entre el Nudo de Castellbisbal y la frontera francesa con los trayectos entre el Nudo de Vila-seca, Sant Vicen\u00e7 de Calders y Martorell; as\u00ed como con otras actuaciones en marcha en las Comunidades Aut\u00f3nomas por las que discurre el Corredor.<\/p>\n<p>Este tramo es indispensable para garantizar la conexi\u00f3n del \u00e1rea de Tarragona con el sur del eje mediterr\u00e1neo de la pen\u00ednsula y con el norte de Catalunya y la frontera francesa a trav\u00e9s de la l\u00ednea interior de Vilafranca del Pened\u00e8s, la conexi\u00f3n con el n\u00facleo estrat\u00e9gico de Castellbisbal y desde ah\u00ed hasta la frontera francesa a trav\u00e9s del ramal Mollet-El Papiol, el Nudo de Mollet y la L\u00ednea de Alta Velocidad a Francia.<\/p>\n<p><strong>Estas obras no solo est\u00e1n orientadas a la potenciaci\u00f3n del tr\u00e1fico de mercanc\u00edas por ferrocarril, sino que tambi\u00e9n beneficiar\u00e1n al transporte de viajeros.<\/strong><br \/>\n<strong>Entre esas ventajas, destacan:<\/strong><br \/>\n&#8211; Infraestructuras e instalaciones m\u00e1s modernas y con mayores par\u00e1metros de eficacia, eficiencia, disponibilidad, funcionalidad, resiliencia, calidad y confort.<br \/>\n&#8211; Mejora de los tiempos de viaje gracias a la adaptaci\u00f3n de la infraestructura para el paso de trenes a una velocidad m\u00e1xima de 120 km\/hora y la eliminaci\u00f3n de limitaciones temporales de velocidad.<br \/>\n&#8211; Racionalizaci\u00f3n de las necesidades de mantenimiento al contar con infraestructuras, elementos estructurales y sistemas m\u00e1s robustos y de mayor durabilidad, que reducen la probabilidad de incidencias.<br \/>\n&#8211; Menor impacto del sistema ferroviario gracias a la construcci\u00f3n de pantallas de protecci\u00f3n ac\u00fastica.<\/p>\n<p>El t\u00fanel de Roda de Ber\u00e0, de 422 metros de longitud, es la infraestructura m\u00e1s singular del tramo Tarragona-Sant Vicen\u00e7 de Calders, en la l\u00ednea que conecta con Barcelona, tanto por la costa (Vilanova), como por el interior (Vilafranca) y utilizada por una media de 120 circulaciones diarias de viajeros y de mercanc\u00edas.<\/p>\n<p>Para su integraci\u00f3n en el Corredor Mediterr\u00e1neo se acomete su adaptaci\u00f3n al ancho internacional y rehabilitaci\u00f3n, tanto en la plataforma como en los elementos estructurales (b\u00f3vedas o paredes laterales, entre otros). Con las obras en marcha se alcanzar\u00e1n ambos objetivos: unas instalaciones adaptadas a los est\u00e1ndares de interoperabilidad necesarios para la circulaci\u00f3n de trenes de mercanc\u00edas en ambos anchos y una infraestructura con m\u00e1ximos niveles de estabilidad estructural, durabilidad y robustez, donde adem\u00e1s se eliminar\u00e1 la limitaci\u00f3n temporal de velocidad existente.<\/p>\n<p><strong>Caracter\u00edsticas t\u00e9cnicas de la actuaci\u00f3n<\/strong><br \/>\nLas obras contemplan la ampliaci\u00f3n del t\u00fanel para adaptarlo al ancho mixto mediante la implantaci\u00f3n del tercer carril en ambas v\u00edas, lo que permitir\u00e1 la circulaci\u00f3n de trenes de ancho est\u00e1ndar e ib\u00e9rico.<\/p>\n<p>Para ello, se est\u00e1n aumentando las dimensiones de la secci\u00f3n actual mediante el rebaje de la rasante en 1,5 metros aproximadamente para cumplir con los est\u00e1ndares de interoperabilidad que requiere el tercer carril. En el interior del t\u00fanel, adem\u00e1s, se est\u00e1 reparando e impermeabilizando la b\u00f3veda e instalando un nuevo sistema de drenaje de aguas. Con respecto a la superestructura, se montar\u00e1 v\u00eda en placa y nueva catenaria y se repondr\u00e1n las instalaciones de seguridad y comunicaciones.<\/p>\n<p>Por su parte, en el exterior del t\u00fanel, tambi\u00e9n se est\u00e1 rebajando la rasante de las v\u00edas y se instalar\u00e1 igualmente v\u00eda en placa (la configuraci\u00f3n m\u00e1s indicada en t\u00faneles) en los tramos contiguos al t\u00fanel, se construir\u00e1n muretes guardabalasto, y se ejecutan dep\u00f3sitos de recogida de vertidos a ambos lados. Del mismo modo, y derivado de los estudios de ruidos y vibraciones realizados previamente a las obras, se prev\u00e9 la colocaci\u00f3n de mantas antivibratorias en las v\u00edas y pantallas ac\u00fasticas en los laterales del tramo para mitigar el impacto generado por las circulaciones ferroviarias.<\/p>\n<p><strong>Avance de los trabajos<\/strong><br \/>\nEl grado de ejecuci\u00f3n actual de las obras es de alrededor de un 70%. El ritmo de trabajos avanza seg\u00fan la planificaci\u00f3n prevista y se mantiene la previsi\u00f3n de finalizaci\u00f3n para principios del pr\u00f3ximo mes de marzo. Hasta el momento, se han realizado las siguientes actuaciones:<\/p>\n<p><strong>&#8211; En el \u00e1mbito del t\u00fanel de Roda de Ber\u00e0:<\/strong><br \/>\n\u00b7 En el interior del t\u00fanel se ha completado el desmontaje de v\u00eda, catenaria y de las redes de cableado de instalaciones.<br \/>\n\u00b7 Los trabajos de bulonado (refuerzo mediante elementos met\u00e1licos de las paredes laterales del t\u00fanel) y de gunitado (proyecciones de hormig\u00f3n tambi\u00e9n para el refuerzo de las paredes laterales) se han finalizado en su totalidad. Tambi\u00e9n se ha finalizado el rebaje de la plataforma ferroviaria para adecuar las dimensiones a la secci\u00f3n del ancho est\u00e1ndar, y el recalce de la totalidad de los hastiales del t\u00fanel en mina.<br \/>\n\u00b7 Se ha recalzado toda la zona de aletas interiores del lado Sant Vicen\u00e7 de Calders y la parte de falso t\u00fanel.<br \/>\n\u00b7 En el exterior del t\u00fanel ya se ha completado el rebaje de la cota de la plataforma ferroviaria, as\u00ed como el desmontaje de la catenaria y el levante de los elementos de la superestructura de v\u00eda. Actualmente se trabaja en la formaci\u00f3n de las capas de coronaci\u00f3n y de subbalasto.<br \/>\n\u00b7 Contin\u00faan las perforaciones de pilotes de cimentaci\u00f3n de pantallas ac\u00fasticas y de los postes de catenaria. Los trabajos de micropilotaje del dep\u00f3sito situado en el PK 0+400 est\u00e1n finalizados.<br \/>\n\u00b7 Se han demolido las aletas exteriores de la boca lado Tarragona y se han reforzado los taludes.<\/p>\n<p>Las obras movilizan actualmente 60 trabajadores y varios equipos de maquinaria de excavaci\u00f3n, perforaci\u00f3n y hormigonado (2 dumpers, 1 retroexcavadora y 1 mixta, 1 pala, 4 ba\u00f1eras, 1 niveladora, 1 rodillo, 2 pilotadoras, 2 perforadoras, 3 cestas elevadoras, camiones hormigonera, 2 bombas de inyecci\u00f3n y 1 bomba de hormig\u00f3n proyectado, entre otras).<\/p>\n<p><strong>&#8211; En otros puntos del trayecto Tarragona-Sant Vicen\u00e7 de Calders:<\/strong><br \/>\n\u00b7 En la cabecera norte de Tarragona se est\u00e1n llevando a cabo actuaciones de levante, premontaje y traslado de desv\u00edos, y operaciones en catenaria y otros elementos.<br \/>\n\u00b7 En la estaci\u00f3n de Altafulla se han culminado los trabajos de desbroce y limpieza, mientras que en la nueva v\u00eda 4 ya se han completado las operaciones en la capa de balasto, la colocaci\u00f3n de traviesas y de carril y se est\u00e1n llevando a cabo tratamientos en los elementos de v\u00eda. En esta estaci\u00f3n, tambi\u00e9n se ha prolongado el paso inferior peatonal, y se ha ampliado y acondicionado el and\u00e9n para dar servicio a la nueva v\u00eda 4.<br \/>\n\u00b7 En el trayecto Torredembarra-Altafulla ya se ha finalizado la sustituci\u00f3n de carriles y se est\u00e1 actuando en la capa de balasto.<br \/>\n\u00b7 Tambi\u00e9n se ha iniciado la instalaci\u00f3n del tercer carril.<br \/>\n\u00b7 En la estaci\u00f3n de Torredembarra se ha completado el levante de v\u00eda y el rebaje de la rasante de la capa de balasto en las cabeceras de la estaci\u00f3n. Los aparatos de v\u00eda est\u00e1n totalmente instalados y actualmente se est\u00e1n adaptando los bordes de andenes a los g\u00e1libos de proyecto.<br \/>\n\u00b7 En la cabecera sur de Sant Vicen\u00e7 de Calders ya se han iniciado los trabajos previos, as\u00ed como el suministro y montaje de los primeros desv\u00edos de ancho mixto a instalar en la estaci\u00f3n.<\/p>\n<p>Actualmente est\u00e1n trabajando 40 operarios en el tramo del Corredor Mediterr\u00e1neo entre Sant Vicen\u00e7 de Calders y Tarragona y se dispone de maquinaria de v\u00eda de diversa tipolog\u00eda (bateadora y estabilizador din\u00e1mico, perfiladora, locomotora con plataformas y tolvas, etc.).<\/p>\n<p><strong>Principales magnitudes<\/strong><br \/>\n&#8211; Retirada de 4.800 m de catenaria, 4.600 m de v\u00eda y 5.420 m3 de balasto.<br \/>\n&#8211; 26.100 m de bulones para el sostenimiento en t\u00fanel.<br \/>\n&#8211; Excavaci\u00f3n y rebaje de la plataforma: 18.800 m3.<br \/>\n&#8211; 8.500 m2 de l\u00e1mina de espuma de polietileno, 8.000 m2 de l\u00e1mina de PVC, 12.000 m2 de geotextil y 110 m3 de hormig\u00f3n proyectado con fibras para impermeabilizaciones en el t\u00fanel.<br \/>\n&#8211; Nueva losa inferior de 2.000 m3 y colocaci\u00f3n de 1.000 m3 de hormig\u00f3n para v\u00eda en placa en el interior del t\u00fanel y de 7.800 m2 de manta antivibratoria.<br \/>\n&#8211; Ejecuci\u00f3n de 500 pilotes (2.130 m de perforaci\u00f3n) para la instalaci\u00f3n de casi 8.000 m2 de pantallas ac\u00fasticas, con una longitud de 1.719 m.<br \/>\n&#8211; 1.350 m de micropilotes para la realizaci\u00f3n de 2 nuevos dep\u00f3sitos de vertidos de 15 m x 3,5 m x 3 m.<br \/>\n&#8211; 520 m de murete guardabalasto.<br \/>\n&#8211; Montaje de 1.020 m de v\u00eda en placa y 1.230 m de v\u00eda sobre balasto.<br \/>\n&#8211; Instalaci\u00f3n de dos cambiadores de hilo.<br \/>\n&#8211; Drenaje e instalaci\u00f3n de 2.640 m de canaletas.<br \/>\n&#8211; Operaciones en sistemas y elementos de electrificaci\u00f3n e instalaci\u00f3n de 4.220 m de nuevo hilo de contacto.<br \/>\n&#8211; Entre la cabecera norte de la estaci\u00f3n de Tarragona y la estaci\u00f3n de Torredembarra, instalaci\u00f3n de 28 aparatos de v\u00eda, sustituci\u00f3n de 96 km de carril de las v\u00edas generales, de apartado y auxiliares y de 8.500 traviesas y se colocaci\u00f3n de 59.621 m de tercer carril.<br \/>\n&#8211; En la estaci\u00f3n de Sant Vicen\u00e7 de Calders, montaje de 23 aparatos de v\u00eda, colocaci\u00f3n de 10.900 traviesas, 19 km de carril, 84 postes nuevos de catenaria y 8 p\u00f3rticos y tendido de 27,5 km de cableado conductor para la l\u00ednea a\u00e9rea de contacto.<\/p>\n<p>El Corredor Mediterr\u00e1neo: eje estrat\u00e9gico para la competitividad y la conexi\u00f3n con Europa<br \/>\nEl Corredor Mediterr\u00e1neo es un proyecto estrat\u00e9gico y v\u00eda preferente de las conexiones de Espa\u00f1a con Europa. En su rama litoral, su desarrollo contribuir\u00e1 a vertebrar el territorio al unir Andaluc\u00eda, Regi\u00f3n de Murcia, Comunitat Valenciana y Catalunya con Europa en ancho est\u00e1ndar. Asimismo, promover\u00e1 una movilidad interoperable y m\u00e1s sostenible y competitividad para las empresas del Arco Mediterr\u00e1neo y su \u00e1rea de influencia, impulsando el transporte de mercanc\u00edas por ferrocarril.<\/p>\n<p>La ejecuci\u00f3n del Corredor Mediterr\u00e1neo se ha convertido en una palanca de recuperaci\u00f3n econ\u00f3mica, contribuyendo al crecimiento econ\u00f3mico y la creaci\u00f3n de empleo. El proyecto se ha convertido tambi\u00e9n en una herramienta para la lucha contra el cambio clim\u00e1tico: su contribuci\u00f3n a la descarbonizaci\u00f3n del transporte se concreta en una disminuci\u00f3n de hasta 5,5 millones de tn\/a\u00f1o de emisiones de CO2 a la atm\u00f3sfera.<\/p>\n<p>El ejercicio de 2024 se cerr\u00f3 con una inversi\u00f3n hist\u00f3rica en el Corredor Mediterr\u00e1neo, ya que el valor global de las obras ejecutadas ascendi\u00f3 a 1.280 millones de euros, un 33 por ciento m\u00e1s que en 2023, cuando la inversi\u00f3n realizada alcanz\u00f3 los 964 millones de euros. Este ritmo r\u00e9cord de ejecuci\u00f3n confirma la fuerte apuesta del Ministerio por desarrollar esta infraestructura que busca mejorar la conectividad ferroviaria desde Algeciras hasta la frontera con Francia. En concreto, en el Corredor Mediterr\u00e1neo se licitaron el pasado a\u00f1o 65 contratos por 1.400 millones euros, un 11,3 por ciento m\u00e1s.<\/p>\n<p>Estas actuaciones contribuyen a la consecuci\u00f3n del Objetivo de Desarrollo Sostenible (ODS) 9, que fomenta infraestructuras fiables, sostenibles y de calidad.<\/p>\n<p><strong>Financiaci\u00f3n europea<\/strong><br \/>\nEsta actuaci\u00f3n podr\u00e1 ser cofinanciada por el Mecanismo \u201cConectar Europa\u201d de la Uni\u00f3n Europea (CEF).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actuaci\u00f3n esencial para el desarrollo del Corredor Mediterr\u00e1neo en Catalunya \u00b7 Se mantiene la planificaci\u00f3n prevista para restablecer el tr\u00e1fico<\/p>\n","protected":false},"author":4,"featured_media":39125,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[818],"tags":[71,986,786,87,961,1636,249,32,274],"class_list":["post-39124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notes-de-premsa","tag-adif","tag-alta-velocidad","tag-ancho-uic-estandar","tag-corredor-del-mediterrani","tag-infraestructuras","tag-ministerio-de-transportes","tag-sant-vicenc-de-calders","tag-tarragona","tag-tercer-carril","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/39124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=39124"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/39124\/revisions"}],"predecessor-version":[{"id":39126,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/39124\/revisions\/39126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media\/39125"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=39124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=39124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=39124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}