{"id":37180,"date":"2023-11-23T11:45:23","date_gmt":"2023-11-23T10:45:23","guid":{"rendered":"https:\/\/www.agrupament.cat\/portal\/?p=37180"},"modified":"2023-11-23T11:45:23","modified_gmt":"2023-11-23T10:45:23","slug":"adif-licita-una-due-diligence-tecnica-de-sus-activos-de-telecomunicaciones","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2023\/11\/adif-licita-una-due-diligence-tecnica-de-sus-activos-de-telecomunicaciones\/","title":{"rendered":"Adif licita una due diligence t\u00e9cnica de sus activos de telecomunicaciones"},"content":{"rendered":"<p>Previamente a la b\u00fasqueda de un socio industrial y estrat\u00e9gico en este \u00e1mbito<br \/>\n<strong>\u00b7 Los activos de telecomunicaciones de Adif y Adif AV est\u00e1n integrados por m\u00e1s de 24.000 km de fibra \u00f3ptica, 1.800 edificaciones t\u00e9cnicas y m\u00e1s de 700 emplazamientos de comunicaciones m\u00f3viles<\/strong><\/p>\n<p>23 NOVIEMBRE 2023<br \/>\nAdif lanza la licitaci\u00f3n de una Due Diligence T\u00e9cnica (DDT) de sus activos de telecomunicaciones con el objetivo de disponer de un an\u00e1lisis independiente de los aspectos m\u00e1s relevantes en este \u00e1mbito. Esta auditor\u00eda, que aportar\u00e1 confianza a la informaci\u00f3n de estos activos de Adif y Adif AV, se realiza con car\u00e1cter previo a una posible b\u00fasqueda de un socio industrial y estrat\u00e9gico para la explotaci\u00f3n conjunta de los activos de telecomunicaciones que Adif y Adif AV.<\/p>\n<p>Llegado este momento, la DDT contribuir\u00e1 a que los candidatos a una posible selecci\u00f3n de un socio industrial no condicionen sus ofertas vinculantes a una posterior revisi\u00f3n del conjunto de activos, evitando as\u00ed dilatar el proceso.<\/p>\n<p>La licitaci\u00f3n determinar\u00e1 las condiciones de la elaboraci\u00f3n de esta due diligence t\u00e9cnica de los activos de telecomunicaciones de Adif y Adif AV de distintas tipolog\u00edas: ductos, fibra \u00f3ptica, parques de telecomunicaciones, salas y cuartos de comunicaciones y emplazamientos de comunicaciones m\u00f3viles, ubicados en todo el territorio nacional.<\/p>\n<p>La revisi\u00f3n de activos tanto documental como de campo se realizar\u00eda atendiendo a las especiales circunstancias del entorno ferroviario en el que se encuentran ubicados. El adjudicatario realizar\u00e1 una due diligence cubriendo una muestra relevante que asegure la fiabilidad del an\u00e1lisis. Este trabajo se realizar\u00e1 en un plazo de dos meses.<\/p>\n<p>Entre las l\u00edneas de an\u00e1lisis de Adif y Adif AV en el sector e telecomunicaci\u00f3n estar\u00eda, en un futuro, la selecci\u00f3n de un socio industrial para consolidar su posici\u00f3n en el mercado de las telecomunicaciones y convertirse en un operador neutro de referencia en Espa\u00f1a. De esta forma, desarrollar\u00edan una l\u00ednea de negocio en torno a sus infraestructuras de telecomunicaciones, actuales y futuras, que contribuya a ampliar sus capacidades de despliegue y explotaci\u00f3n y optimice la comercializaci\u00f3n de estos activos, con el fin de liderar el proceso de digitalizaci\u00f3n de la movilidad ferroviaria y apoyar el desarrollo de la sociedad de la informaci\u00f3n en Espa\u00f1a.<\/p>\n<p>Previamente, el gestor de infraestructuras ya realiz\u00f3 una consulta preliminar al mercado para evaluar alternativas de colaboraci\u00f3n, impulsar nuevas inversiones y optimizar la explotaci\u00f3n y comercializaci\u00f3n de sus activos en este \u00e1mbito.<\/p>\n<p>Adif y Adif AV cuentan con un patrimonio integrado por m\u00e1s de 15.000 km de v\u00edas sobre el que despliegan infraestructuras de telecomunicaciones -fibra \u00f3ptica de m\u00e1s de 24.000 km, 1.800 edificaciones t\u00e9cnicas y m\u00e1s de 700 emplazamientos de comunicaciones m\u00f3viles- que contribuyen a una mejor gesti\u00f3n de la operaci\u00f3n y la explotaci\u00f3n ferroviaria.<\/p>\n<p>El alcance de las actuaciones que se realizar\u00eda con la selecci\u00f3n de un posible socio figurar\u00eda el desarrollo, operaci\u00f3n, mantenimiento y comercializaci\u00f3n de las infraestructuras de telecomunicaciones (banda ancha fija y m\u00f3vil, activos inmobiliarios y espacios), as\u00ed como el desarrollo, gesti\u00f3n, soporte y comercializaci\u00f3n de servicios prestados sobre dichas infraestructuras (fibra oscura e iluminada, conectividad IoT, servicios mayoristas de infraestructura neutra pasiva y activa, etc.).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previamente a la b\u00fasqueda de un socio industrial y estrat\u00e9gico en este \u00e1mbito \u00b7 Los activos de telecomunicaciones de Adif<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[818],"tags":[71,986],"class_list":["post-37180","post","type-post","status-publish","format-standard","hentry","category-notes-de-premsa","tag-adif","tag-alta-velocidad","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/37180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=37180"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/37180\/revisions"}],"predecessor-version":[{"id":37181,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/37180\/revisions\/37181"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=37180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=37180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=37180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}