{"id":35826,"date":"2022-05-17T17:28:43","date_gmt":"2022-05-17T16:28:43","guid":{"rendered":"https:\/\/www.agrupament.cat\/portal\/?p=35826"},"modified":"2022-05-17T17:32:29","modified_gmt":"2022-05-17T16:32:29","slug":"el-gobierno-autoriza-la-licitacion-de-las-obras-de-remodelacion-e-implantacion-del-ancho-estandar-en-la-terminal-de-valencia-font-de-sant-lluis","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2022\/05\/el-gobierno-autoriza-la-licitacion-de-las-obras-de-remodelacion-e-implantacion-del-ancho-estandar-en-la-terminal-de-valencia-font-de-sant-lluis\/","title":{"rendered":"El Gobierno autoriza la licitaci\u00f3n de las obras de remodelaci\u00f3n e implantaci\u00f3n del ancho est\u00e1ndar en la terminal de Val\u00e8ncia-Font de Sant Llu\u00eds"},"content":{"rendered":"<p>Avances en el Corredor Mediterr\u00e1neo<\/p>\n<p><strong>\u00b7 El contrato cuenta con un valor estimado superior a los 40 millones de euros, de los que m\u00e1s de 22 millones corresponden a suministros.<\/strong><br \/>\n<strong>\u00b7 Se desarrollar\u00e1n actuaciones en v\u00eda y de electrificaci\u00f3n destinadas a la implantaci\u00f3n del ancho mixto en este tramo, garantizando la adecuada prestaci\u00f3n, capacidad, estabilidad y fiabilidad de los tr\u00e1ficos de viajeros y mercanc\u00edas.<\/strong><br \/>\n<strong>\u00b7 Esta actuaci\u00f3n forma parte de las obras de adaptaci\u00f3n al ancho est\u00e1ndar del Corredor Mediterr\u00e1neo y mejorar\u00e1 la explotaci\u00f3n y el aprovechamiento de la infraestructura al disponer de m\u00e1s v\u00edas en ancho mixto.<\/strong><\/p>\n<p>Madrid, 17 de mayo de 2022 (Mitma).<br \/>\nEl Consejo de Ministros, en su reuni\u00f3n de hoy, ha autorizado al Ministerio de Transportes, Movilidad y Agenda Urbana (Mitma) a licitar, a trav\u00e9s de Adif Alta Velocidad, el contrato para la remodelaci\u00f3n integral y la implantaci\u00f3n del ancho mixto en la terminal de Val\u00e8ncia-Font de Sant Llu\u00eds, situada en el tramo Val\u00e8ncia-Castell\u00f3 del Corredor Mediterr\u00e1neo.<\/p>\n<p>El contrato cuenta con un valor estimado de 40.077.050,65 euros, de los que 22.045.008,81 euros corresponden a suministros, y un plazo de ejecuci\u00f3n de 30 meses.<\/p>\n<p>El proyecto de construcci\u00f3n comprende actuaciones en v\u00eda y de electrificaci\u00f3n destinadas a la implantaci\u00f3n del ancho mixto en el tramo correspondiente a Val\u00e8ncia-Font de Sant Llu\u00eds, tanto en sus v\u00edas generales como en las v\u00edas de apartado que as\u00ed lo requieran, adaptando las instalaciones y elementos de la l\u00ednea que sea preciso para la correcta explotaci\u00f3n de la longitud de tren est\u00e1ndar interoperable (750 m) y garantizando la adecuada prestaci\u00f3n, capacidad, estabilidad y fiabilidad de los tr\u00e1ficos de viajeros y mercanc\u00edas.<\/p>\n<p>Esta actuaci\u00f3n reafirma el compromiso del Ministerio de Transportes, Movilidad y Agenda Urbana (Mitma) y de Adif AV con la planificaci\u00f3n y el desarrollo del Corredor Mediterr\u00e1neo, mediante nuevas actuaciones que impulsan y avanzan en la construcci\u00f3n de esta infraestructura estrat\u00e9gica para la mejora de las prestaciones a los viajeros en ancho est\u00e1ndar ya que, cuando finalicen, se dispondr\u00e1 de m\u00e1s v\u00edas por las que se podr\u00e1 circular tanto en ancho convencional (1.668 mm) como en ancho est\u00e1ndar (1.435 mm). Adem\u00e1s, en un futuro pr\u00f3ximo permitir\u00e1n los tr\u00e1nsitos de mercanc\u00edas en ancho est\u00e1ndar desde o hacia Europa.<\/p>\n<p>Est\u00e1 previsto que estos trabajos se desarrollen principalmente en horario nocturno y en fines de semana, con el fin de minimizar las afectaciones al tr\u00e1fico de trenes.<\/p>\n<p>Estas obras contribuyen a la consecuci\u00f3n del Objetivo de Desarrollo Sostenible (ODS) n\u00famero 9, que tiene entre sus metas desarrollar infraestructuras fiables, sostenibles y de calidad.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Descripci\u00f3n de las obras<\/strong><\/span><br \/>\n<strong>Las principales actuaciones que contempla el proyecto son las siguientes:<\/strong><br \/>\n\u00b7 Adaptaci\u00f3n de la geometr\u00eda de v\u00eda (entrev\u00edas, g\u00e1libos cinem\u00e1ticos, etc.) a la implantaci\u00f3n del ancho mixto<br \/>\n\u00b7 Renovaci\u00f3n y\/o adaptaci\u00f3n de superestructura de v\u00eda existente al ancho mixto: balastos, traviesas, carril y desv\u00edos<br \/>\n\u00b7 Revisi\u00f3n y adecuaci\u00f3n de la electrificaci\u00f3n existente a la implantaci\u00f3n de diferentes anchos de v\u00eda (UIC y mixto) y de la nueva configuraci\u00f3n y topolog\u00eda de v\u00edas. Todo ello, manteniendo la tensi\u00f3n actual a 3 kV c.c.<br \/>\n\u00b7 Reposici\u00f3n de servicios afectados y adecuaci\u00f3n del drenaje existente.<\/p>\n<p><strong>Todas las actuaciones previstas necesarias y desarrolladas en el proyecto de construcci\u00f3n, se fundamentan en las siguientes premisas:<\/strong><br \/>\n\u00b7 Maximizaci\u00f3n del aprovechamiento de instalaciones existentes con objeto de optimizar la inversi\u00f3n asociada a la actuaci\u00f3n.<br \/>\n\u00b7 Minimizaci\u00f3n de actuaciones fuera de los l\u00edmites del actual Dominio P\u00fablico Ferroviario con objeto de evitar posibles afecciones medioambientales y minimizar los plazos de tramitaci\u00f3n asociados.<br \/>\n\u00b7 Definici\u00f3n de un plan de obra que garantice en todo momento una adecuada prestaci\u00f3n del servicio ferroviario en condiciones de plena seguridad, optimice los plazos de ejecuci\u00f3n y permita extender lo antes posible las ventajas funcionales y comerciales de la implantaci\u00f3n del ancho mixto.<br \/>\nEn lo que a mercanc\u00edas se refiere, uno de los \u00e1mbitos con mayor generaci\u00f3n de tr\u00e1ficos es el Corredor Mediterr\u00e1neo, que cuenta, entre otros, con importantes Puertos de la Red de Inter\u00e9s General como nodos principales de actividad, entre ellos el Port de Val\u00e8ncia.<\/p>\n<p>Mediante la llegada del ancho est\u00e1ndar a los principales puertos y nodos del Corredor Mediterr\u00e1neo, el Mitma trata de impulsar un potente desarrollo del modo ferroviario en el contexto del transporte nacional e internacional de mercanc\u00edas, a fin de crear un sistema eficiente que permita aumentar su cuota de participaci\u00f3n global hasta alcanzar valores similares a los del resto de Europa, con las indudables ventajas sociales, econ\u00f3micas y ambientales que ello conllevar\u00e1.<\/p>\n<p><strong>Financiaci\u00f3n europea<\/strong><br \/>\nEsta actuaci\u00f3n podr\u00e1 ser cofinanciada por el Mecanismo \u201cConectar Europa\u201d de la Uni\u00f3n Europea (CEF).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avances en el Corredor Mediterr\u00e1neo \u00b7 El contrato cuenta con un valor estimado superior a los 40 millones de euros,<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[818],"tags":[786,87,69,884,1504],"class_list":["post-35826","post","type-post","status-publish","format-standard","hentry","category-notes-de-premsa","tag-ancho-uic-estandar","tag-corredor-del-mediterrani","tag-mitva-ministerio-de-fomento","tag-projecte","tag-valencia-font-de-sant-lluis","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=35826"}],"version-history":[{"count":3,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35826\/revisions"}],"predecessor-version":[{"id":35829,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35826\/revisions\/35829"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=35826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=35826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=35826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}