{"id":35636,"date":"2022-04-28T19:10:21","date_gmt":"2022-04-28T18:10:21","guid":{"rendered":"https:\/\/www.agrupament.cat\/portal\/?p=35636"},"modified":"2022-04-28T19:10:21","modified_gmt":"2022-04-28T18:10:21","slug":"adif-adjudica-por-mas-de-45-me-la-construccion-de-un-paso-superior-en-cullera-valencia","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2022\/04\/adif-adjudica-por-mas-de-45-me-la-construccion-de-un-paso-superior-en-cullera-valencia\/","title":{"rendered":"Adif adjudica por m\u00e1s de 4,5 M\u20ac la construcci\u00f3n de un paso superior en Cullera (Valencia)"},"content":{"rendered":"<p>En el marco del Plan de Cercan\u00edas de la Comunitat Valenciana<br \/>\n<strong>\u00b7 El nuevo paso superior permitir\u00e1 integrar y permeabilizar la infraestructura con el fin de incrementar las condiciones de seguridad tanto para los ciudadanos como para las circulaciones ferroviarias<\/strong><\/p>\n<p>27 ABRIL 2022<br \/>\nAdif ha adjudicado las obras para la construcci\u00f3n de un paso superior que permitir\u00e1 la supresi\u00f3n de un paso a nivel en el p.k. 32\/082, situado en el t\u00e9rmino municipal de Cullera (Valencia), correspondiente a la l\u00ednea de la red ferroviaria convencional Silla-Gand\u00eda.<\/p>\n<p>El contrato, adjudicado por importe de 4.693.609,08 euros (IVA incluido) a la empresa Torrescamara y CIA de Obras, cuenta con un plazo de ejecuci\u00f3n de obras de 12 meses.<\/p>\n<p>Estos trabajos, que se enmarcan dentro del Plan de Cercan\u00edas de la Comunidad Valenciana 2017-2025, tienen por objetivo integrar y permeabilizar la infraestructura ferroviaria en un punto ubicado a aproximadamente 5 km de la estaci\u00f3n de Cullera (lado Gand\u00eda).<\/p>\n<p>Adif ha adjudicado las obras para la construcci\u00f3n de un paso superior que permitir\u00e1 la supresi\u00f3n de un paso a nivel en el p.k. 32\/082, situado en el t\u00e9rmino municipal de Cullera (Valencia), correspondiente a la l\u00ednea de la red ferroviaria convencional Silla-Gand\u00eda.<\/p>\n<p>El contrato, adjudicado por importe de 4.693.609,08 euros (IVA incluido) a la empresa Torrescamara y CIA de Obras, cuenta con un plazo de ejecuci\u00f3n de obras de 12 meses.<\/p>\n<p>Estos trabajos, que se enmarcan dentro del Plan de Cercan\u00edas de la Comunidad Valenciana 2017-2025, tienen por objetivo integrar y permeabilizar la infraestructura ferroviaria en un punto ubicado a aproximadamente 5 km de la estaci\u00f3n de Cullera (lado Gand\u00eda).<\/p>\n<p><strong>Descripci\u00f3n de las obras<\/strong><br \/>\nLos trabajos adjudicados comprenden la ejecuci\u00f3n de las siguientes operaciones:<br \/>\n&#8211; Construcci\u00f3n de la estructura de un paso superior para veh\u00edculos y peatones, con un g\u00e1libo de 7 m.<br \/>\n&#8211; Ejecuci\u00f3n de 4 caminos de enlace para reponer la accesibilidad a las fincas colindantes.<br \/>\n&#8211; Trabajos de drenaje transversal y longitudinal. Medidas destinadas a prevenir el deterioro por filtraci\u00f3n de aguas como son bordillos, terraplenes y cunetas.<br \/>\n&#8211; Se\u00f1alizaci\u00f3n vertical y horizontal y sistemas de contenci\u00f3n en los bordes (defensas, pretiles, barandillas, etc.)<br \/>\n&#8211; Reposici\u00f3n de canalizaciones, l\u00edneas el\u00e9ctricas, sistemas de se\u00f1alizaci\u00f3n y comunicaciones.<br \/>\n&#8211; Clausura del paso a nivel mediante desmantelamiento de los elementos de campo y disposici\u00f3n de barreras de contenci\u00f3n en cada una de las m\u00e1rgenes.<\/p>\n<p>Este contrato forma parte de las actuaciones previstas por Adif para la supresi\u00f3n y mejora de la protecci\u00f3n de pasos a nivel en la Red Ferroviaria de Inter\u00e9s General con el fin de incrementar las condiciones de seguridad de las infraestructuras de transporte, tanto para los ciudadanos como para las circulaciones ferroviarias.<\/p>\n<p>Estas actuaciones reafirman el compromiso del Ministerio de Transportes, Movilidad y Agenda Urbana (MITMA) y de Adif para la mejora de las l\u00edneas de la red convencional en la Comunidad Valenciana, y contribuye a la consecuci\u00f3n de diferentes Objetivos de Desarrollo Sostenible, como el ODS 9 (Industria, Innovaci\u00f3n e Infraestructura) y el 11 (Ciudades y Comunidades Sostenibles).<\/p>\n<p><strong>Financiaci\u00f3n europea<\/strong><br \/>\nEsta actuaci\u00f3n podr\u00e1 ser cofinanciada por el Mecanismo \u201cConectar Europa\u201d de la Uni\u00f3n Europea (CEF).<\/p>\n<p>\u201cUna manera de hacer Europa\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del Plan de Cercan\u00edas de la Comunitat Valenciana \u00b7 El nuevo paso superior permitir\u00e1 integrar y permeabilizar<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[818],"tags":[71,792,169,961],"class_list":["post-35636","post","type-post","status-publish","format-standard","hentry","category-notes-de-premsa","tag-adif","tag-ancho-iberico","tag-comunidad-valenciana","tag-infraestructuras","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=35636"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35636\/revisions"}],"predecessor-version":[{"id":35637,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35636\/revisions\/35637"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=35636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=35636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=35636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}