{"id":35227,"date":"2022-03-09T08:00:35","date_gmt":"2022-03-09T07:00:35","guid":{"rendered":"https:\/\/www.agrupament.cat\/portal\/?p=35227"},"modified":"2022-03-10T17:35:53","modified_gmt":"2022-03-10T16:35:53","slug":"renfe-manda-al-coche-del-silencio-los-mensajes-de-odio-contra-las-mujeres-en-redes-sociales","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2022\/03\/renfe-manda-al-coche-del-silencio-los-mensajes-de-odio-contra-las-mujeres-en-redes-sociales\/","title":{"rendered":"Renfe manda al \u2018coche del silencio\u2019 los mensajes de odio contra las mujeres en redes sociales"},"content":{"rendered":"<p>Campa\u00f1a institucional con motivo del D\u00eda Internacional de la Mujer<br \/>\n<strong>\u00b7 Bajo el lema \u2018En el viaje hacia la igualdad, silenciemos el odio\u2019, Renfe promueve la eliminaci\u00f3n de comentarios machistas y tweets mis\u00f3ginos<\/strong><br \/>\n<strong>\u00b7 Renfe se suma al D\u00eda Internacional de la Mujer para mostrar su compromiso con la igualdad de las mujeres y promover una cultura empresarial de compromiso con la igualdad de g\u00e9nero<\/strong><\/p>\n<p>Madrid, 8 de marzo de 2022 (Renfe).<br \/>\nRenfe ha lanzado hoy una campa\u00f1a institucional, con motivo del D\u00eda Internacional de la Mujer, en la que manda al \u2018coche del silencio\u2019 los mensajes de odio contra las mujeres existentes en redes sociales.<\/p>\n<p>Bajo el lema \u2018En el viaje hacia la igualdad, silenciemos el odio\u2019, Renfe promueve la eliminaci\u00f3n de comentarios machistas, tweets mis\u00f3ginos y opiniones no fundamentadas y absurdas sobre la mujer que suelen publicarse en redes.<\/p>\n<p>En el video, aparecen dos trabajadores de Renfe colocando distintos recortes y hojas de papel con comentarios de \u00edndole machista, en las paredes y el techo del coche de un tren. Se pueden leer tweets como \u201cCalladita est\u00e1is m\u00e1s guapas\u201d, \u201cSolo eres la mujer de\u2026\u201d o \u201c\u00bf\u00c1rbitra? Pero qu\u00e9 broma es esta\u201d, entre otros.<\/p>\n<p>Cuando los operarios acaban su trabajo y han empapelado todo el coche del tren, salen del mismo, se cierran las puertas y se puede leer: \u2018Coche del silencio\u2019.<\/p>\n<p><strong>Compromiso con la igualdad de g\u00e9nero<\/strong><br \/>\nRenfe mantiene un firme compromiso con la igualdad de g\u00e9nero, como recoge su Plan Estrat\u00e9gico, y anima, a trav\u00e9s de distintas iniciativas, a que cada vez m\u00e1s mujeres se interesen y se planteen la posibilidad de trabajar en la compa\u00f1\u00eda, dando a conocer las diferentes profesiones que pueden desarrollarse dentro de la empresa.<\/p>\n<p>Hist\u00f3ricamente, la mayor\u00eda de trabajadores de Renfe han sido hombres, sobre todo en personal de conducci\u00f3n y talleres. En estos colectivos, la empresa est\u00e1 realizando un esfuerzo especial por tratar de atraer candidatas para los puestos que hay que cubrir. As\u00ed, en los tres \u00faltimos a\u00f1os se han duplicado pr\u00e1cticamente el n\u00famero de mujeres maquinistas que trabajan en nuestra compa\u00f1\u00eda.<\/p>\n<p>Este objetivo tambi\u00e9n se fomenta m\u00e1s all\u00e1 de nuestras fronteras, como se refleja en las pruebas de selecci\u00f3n puestas en marcha por la sucursal de Renfe en Arabia Saud\u00ed para la contrataci\u00f3n de 30 mujeres maquinistas, a las que se presentaron m\u00e1s de 28.000 candidatas de nacionalidad saud\u00ed.<\/p>\n<p><strong>Socialmente responsables<\/strong><br \/>\nRenfe ha incorporado a su estrategia empresarial los Objetivos de Desarrollo Sostenible y su Agenda 2030, aprobados por Naciones Unidas en 2015.<\/p>\n<p>A este respecto, Renfe se suma al D\u00eda Internacional de la Mujer para mostrar su compromiso con la igualdad y promover una cultura empresarial a favor de la igualdad de g\u00e9nero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campa\u00f1a institucional con motivo del D\u00eda Internacional de la Mujer \u00b7 Bajo el lema \u2018En el viaje hacia la igualdad,<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[818],"tags":[1422,72],"class_list":["post-35227","post","type-post","status-publish","format-standard","hentry","category-notes-de-premsa","tag-igualdad","tag-renfe-operadora","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=35227"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35227\/revisions"}],"predecessor-version":[{"id":35228,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35227\/revisions\/35228"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=35227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=35227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=35227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}