{"id":35200,"date":"2022-03-07T10:43:58","date_gmt":"2022-03-07T09:43:58","guid":{"rendered":"https:\/\/www.agrupament.cat\/portal\/?p=35200"},"modified":"2022-03-08T09:57:59","modified_gmt":"2022-03-08T08:57:59","slug":"afectacions-a-la-l5-de-metro","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2022\/03\/afectacions-a-la-l5-de-metro\/","title":{"rendered":"Afectacions a la L5 de metro"},"content":{"rendered":"<p><strong>\u00b7 Des del divendres 11 de mar\u00e7, a les 22 hores fins al final del servei del diumenge 13 de mar\u00e7, el tram de la L5 entre Cornell\u00e0 Centre i Can Boixeres quedar\u00e0 sense servei per obres a la via.<\/strong><br \/>\n<strong>\u00b7 La l\u00ednia funcionar\u00e0 amb normalitat de Can Boixeres a Vall d\u2019Hebron.<\/strong><\/p>\n<p><strong>Recomanacions de transport<\/strong><br \/>\nPer arribar a les estacions del tram afectat entre Cornell\u00e0 Centre i Can Boixeres recomanem:<br \/>\n<strong><span style=\"text-decoration: underline;\">\u00a0* Servei de bus llan\u00e7adora<\/span><\/strong><br \/>\nHi haur\u00e0 un servei de bus llan\u00e7adora entre Cornell\u00e0 Centre i Can Boixeres amb el mateix horari de metro, \u00e9s a dir, el divendres, l\u2019\u00faltim bus far\u00e0 la sortida de les parades d\u2019origen\/final (Cornell\u00e0 Centre i Can Boixeres) a les 2.00 h de la matinada, dissabte funcionar\u00e0 tota la nit i diumenge a les 12.00 de la nit. Aquest horari del servei de bus llan\u00e7adora no garanteix l&#8217;enlla\u00e7 amb l&#8217;\u00faltim tren de metro.<\/p>\n<p><strong>Horari de servei del bus llan\u00e7adora: Temps de pas aproximat:<\/strong><br \/>\nDivendres: cada 6-7 min.<br \/>\nDissabte i diumenge: de les 11 a les 22 hores, cada 5-6 min, la resta del servei, cada 7-9 min.<\/p>\n<p><strong><span style=\"text-decoration: underline;\">* Altres transports<\/span><\/strong><br \/>\n&#8211; Rodalies de Catalunya: podeu fer servir les l\u00ednies R1 i R4 entre les estacions de Cornell\u00e0 Centre i Sants Estaci\u00f3.<br \/>\n&#8211; Avanza: podeu fer servir la l\u00ednia L85 entre les estacions de Cornell\u00e0 Centre i Can Boixeres.<br \/>\n&#8211; TRAM: podeu fer servir les l\u00ednies T1 i T2.<\/p>\n<p><strong>Planifica el teu recorregut<\/strong><br \/>\nAccedeix a l\u2019eina Vull anar, on podr\u00e0s trobar les alternatives de transport.<\/p>\n<p>L\u2019assistent de viatge Vull anar tamb\u00e9 est\u00e0 disponible a la TMB App. \u00c9s gratu\u00efta i est\u00e0 disponible per a dispositius amb sistemes Android o iOS.<\/p>\n<p><strong>M\u00e9s informaci\u00f3<\/strong><br \/>\n&#8211; Consulta les mesures de prevenci\u00f3 pel coronavirus.<br \/>\n&#8211; Per a consultes, TMB t\u00e9 a disposici\u00f3 dels usuaris el tel\u00e8fon d&#8217;informaci\u00f3 i atenci\u00f3 al ciutad\u00e0 900 701 149 (de dilluns a diumenge, de 8 a 21 h) i tamb\u00e9 el compte d\u2019informaci\u00f3 i atenci\u00f3 a Twitter (de dilluns a divendres feiners, de 7 a 20 h).<br \/>\n&#8211; Si vols informar-te d&#8217;altres actuacions previstes que puguin afectar el servei de transport p\u00fablic o b\u00e9 vols accedir a recomanacions de transport, entra a la secci\u00f3 &#8220;Estat del servei&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7 Des del divendres 11 de mar\u00e7, a les 22 hores fins al final del servei del diumenge 13 de<\/p>\n","protected":false},"author":4,"featured_media":35201,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[818],"tags":[17,377,19,109,56],"class_list":["post-35200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notes-de-premsa","tag-afectacions-e-incidencies","tag-cornella-de-llobregat","tag-infraestructures","tag-l05-vall-dhebron-cornella-centre","tag-metro-barcelona-tmb","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=35200"}],"version-history":[{"count":3,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35200\/revisions"}],"predecessor-version":[{"id":35204,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/35200\/revisions\/35204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media\/35201"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=35200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=35200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=35200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}