{"id":34435,"date":"2021-10-28T08:00:00","date_gmt":"2021-10-28T06:00:00","guid":{"rendered":"https:\/\/www.agrupament.cat\/portal\/?p=34435"},"modified":"2021-10-31T13:29:11","modified_gmt":"2021-10-31T11:29:11","slug":"adif-y-adif-av-invertiran-5-424-me-en-la-red-ferroviaria-en-el-ano-2022","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2021\/10\/adif-y-adif-av-invertiran-5-424-me-en-la-red-ferroviaria-en-el-ano-2022\/","title":{"rendered":"Adif y Adif AV invertir\u00e1n 5.424 M\u20ac en la red ferroviaria en el a\u00f1o 2022"},"content":{"rendered":"<p>La presidenta de ambas entidades ha presentado hoy sus presupuestos y l\u00edneas estrat\u00e9gicas en el Congreso de los Diputados<br \/>\n<strong>\u2022 Del total de las inversiones previstas, 2.833 millones de euros se destinar\u00e1n a actuaciones de mejora y renovaci\u00f3n de la red existente y los restantes 2.591 millones de euros al desarrollo de nuevas infraestructuras<\/strong><br \/>\n<strong>\u2022 Los presupuestos presentados por Adif y Adif AV tienen como principal objetivo la mejora continua de la red, favoreciendo la multimodalidad, y con la vertebraci\u00f3n territorial como piedra angular del proyecto<\/strong><br \/>\n<strong>\u2022 Los fondos del Plan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia impulsar\u00e1n un plan de choque de movilidad sostenible, segura y conectada en n\u00facleos de Cercan\u00edas, as\u00ed como el desarrollo de los corredores europeos, la red transeuropea de transportes y la intermodalidad log\u00edstica<\/strong><\/p>\n<p>27\/10\/2021. Adif y Adif Alta Velocidad tienen previsto invertir 5.424 millones de euros en el a\u00f1o 2022, seg\u00fan ha informado la presidenta de ambas entidades, Mar\u00eda Luisa Dom\u00ednguez, en el transcurso de su comparecencia en el Congreso de los Diputados para exponer las l\u00edneas generales de los presupuestos del pr\u00f3ximo ejercicio.<\/p>\n<p>De esta cifra global, un total de 2.833 millones de euros se destinar\u00e1n a actuaciones de mejora y renovaci\u00f3n de la red existente de ancho convencional y de ancho m\u00e9trico, y los restantes 2.591 millones de euros al desarrollo de nuevas infraestructuras. A esta inversi\u00f3n hay que a\u00f1adirle los recursos destinados a mantenimiento, que para 2022 alcanzan la cifra de 930 millones de euros.<\/p>\n<p>Los presupuestos presentados por Adif y Adif AV, que sientan las bases de la recuperaci\u00f3n, est\u00e1n en plena consonancia con los objetivos del Ministerio de Transportes, Movilidad y Agenda Urbana y del Plan de Recuperaci\u00f3n Transformaci\u00f3n y Resiliencia, de modo que a las habituales l\u00edneas de inversi\u00f3n se unen los fondos del citado Plan, lo que hace a los presupuestos a\u00fan m\u00e1s ambiciosos. El principal objetivo es la mejora continua de la red, favoreciendo la multimodalidad y con la vertebraci\u00f3n territorial como piedra angular del proyecto.<\/p>\n<p>Los presupuestos de ambas entidades tienen como centro a la ciudadan\u00eda y la mejora de su movilidad en el d\u00eda a d\u00eda, con un programa de inversiones que abarca tres grandes ejes: el desarrollo de nuevas l\u00edneas, que sirvan para completar la red transeuropea de transportes; la adaptaci\u00f3n y mejora de la red convencional; y la mejora de las conexiones para el tr\u00e1fico de mercanc\u00edas, donde el ferrocarril est\u00e1 llamado a ser un actor fundamental dentro de la movilidad segura, sostenible y eficiente.<\/p>\n<p><strong>Actuaciones para el desarrollo de nuevas l\u00edneas<\/strong><br \/>\nEspa\u00f1a contin\u00faa desarrollando los ejes principales de transporte transeuropeo y consolidando esa red b\u00e1sica con actuaciones que permiten llegar a la inmensa mayor\u00eda del territorio con una red puntera. A los tramos puestos en servicio en los \u00faltimos a\u00f1os se unir\u00e1n pr\u00f3ximamente otros como Pedralba-Ourense, la conexi\u00f3n en ancho est\u00e1ndar entre Chamart\u00edn, Atocha y Torrej\u00f3n de Velasco y el tramo Venta de Ba\u00f1os-Burgos, todos ellos ya en fase de pruebas. Desde esta perspectiva, el objetivo de los presupuestos es dar continuidad a este esfuerzo inversor y avanzar en la culminaci\u00f3n de dicha red.<\/p>\n<p>Al mismo tiempo, la necesidad de absorber la demanda que conlleva el proceso de liberalizaci\u00f3n del transporte ferroviario de viajeros ha hecho necesaria la ampliaci\u00f3n de capacidad en grandes terminales ferroviarias como Chamart\u00edn, Puerta de Atocha y Sants. Ya est\u00e1n en marcha actuaciones que permitir\u00e1n el desarrollo de estos nodos de transporte que se encuentran englobados en el sistema de transportes de la ciudad y que generar\u00e1n nuevas oportunidades de conexi\u00f3n.<\/p>\n<p><strong>Mejora de la red convencional y el transporte de mercanc\u00edas<\/strong><br \/>\nEn lo que respecta a la red convencional, a la que Adif destinar\u00e1 2.833 millones de euros, los objetivos fundamentales son la mejora de la fiabilidad en las l\u00edneas m\u00e1s antiguas &#8211;para contribuir a la vertebraci\u00f3n territorial y la movilidad interregional- &#8211;, y de los n\u00facleos de Cercan\u00edas.<\/p>\n<p>Estos \u00faltimos servicios ferroviarios son estrat\u00e9gicos para facilitar la movilidad urbana e interurbana. Los distintos planes de Cercan\u00edas que est\u00e1n ejecut\u00e1ndose en n\u00facleos como los de Madrid, Barcelona, Valencia\/Alicante\/Murcia, Asturias y Cantabria, junto a otras actuaciones desarrolladas en el resto del territorio, contemplan una previsi\u00f3n de inversi\u00f3n de 1.533 millones de euros para 2022.<\/p>\n<p>Otra prioridad presupuestaria es la potenciaci\u00f3n del transporte de mercanc\u00edas, que implica el desarrollo de corredores europeos, el fomento de la intermodalidad y la modernizaci\u00f3n de las terminales log\u00edsticas y los accesos a los puertos. Para incentivar el transporte intermodal y reducir la congesti\u00f3n del tr\u00e1fico rodado por carretera, entre otros objetivos, Adif est\u00e1 desarrollando los que ser\u00e1n los primeros servicios de autopistas ferroviarias en Espa\u00f1a. De hecho, ya se han suscrito los protocolos para la puesta en servicio de las autopistas ferroviarias Algeciras-Zaragoza y Madrid-Val\u00e8ncia en ancho ib\u00e9rico.<\/p>\n<p>El impulso de los servicios de mercanc\u00edas vendr\u00e1 dado tambi\u00e9n por proyectos como el nuevo acceso ferroviario al Puerto de Castell\u00f3, la mejora y dotaci\u00f3n de ancho UIC de las instalaciones de Can Tunis, la ampliaci\u00f3n a 750 m de las v\u00edas en 19 apartaderos y las inversiones en las terminales log\u00edsticas de Vic\u00e1lvaro, La Llagosta, Val\u00e8ncia-Fuente San Luis y J\u00fandiz.<\/p>\n<p><strong>Plan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia<\/strong><br \/>\nUno de los hitos fundamentales para ambas entidades es la ejecuci\u00f3n y el cumplimiento del Plan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia, que contribuir\u00e1 a acelerar la recuperaci\u00f3n econ\u00f3mica en el corto plazo, generando un fuerte impacto sobre el PIB y el empleo. Dom\u00ednguez ha recordado que, de los 140.000 millones de euros asignados a Espa\u00f1a, un total de 6.243 millones de euros ser\u00e1n inversi\u00f3n directa destinados al sector del ferrocarril. De ellos, 5.874 millones de euros corresponder\u00e1n a Adif y Adif AV.<\/p>\n<p>La componente 1 del Plan tendr\u00e1 una asignaci\u00f3n econ\u00f3mica de 1.476 millones de euros destinada al desarrollo de un plan de choque de movilidad sostenible, segura y conectada en los principales n\u00facleos de Cercan\u00edas.<\/p>\n<p>Asimismo, la componente 6, con una dotaci\u00f3n econ\u00f3mica de 4.397 millones de euros, tiene entre sus principales l\u00edneas de inversi\u00f3n el desarrollo de corredores europeos, con un total de 2.937 millones de euros. Una segunda l\u00ednea de inversi\u00f3n es la red transeuropea de transportes, con un importe de 993 millones de euros. Otra l\u00ednea de inversi\u00f3n principal se centra en la intermodalidad log\u00edstica, con una dotaci\u00f3n de 466 millones de euros, que incluye las actuaciones ya mencionadas anteriormente.<\/p>\n<p><strong>\u00c9xito de la liberalizaci\u00f3n<\/strong><br \/>\nLa presidenta de Adif y Adif AV ha repasado los aspectos m\u00e1s relevantes de la actividad de ambas entidades en los \u00faltimos meses, un per\u00edodo en que el contexto sanitario est\u00e1 siendo m\u00e1s favorable y durante el que se ha presentado el nuevo Plan Estrat\u00e9gico 2030 de Adif y Adif AV, una hoja de ruta para la pr\u00f3xima d\u00e9cada. El cambio clim\u00e1tico, la transici\u00f3n energ\u00e9tica, la sostenibilidad econ\u00f3mica o el relevo generacional se configuran como hitos para poner a disposici\u00f3n de la sociedad un servicio adecuado a sus necesidades.<\/p>\n<p>Dom\u00ednguez ha resaltado especialmente el \u00e9xito de la liberalizaci\u00f3n del transporte de viajeros. El a\u00f1o 2021 ha sido un punto de inflexi\u00f3n en este proceso, con la entrada en servicio de un nuevo operador en el corredor de Alta Velocidad Madrid-Barcelona, Ouigo. En 2022 est\u00e1 previsto que entre en el mercado otra empresa ferroviaria (Ilsa), en principio en el corredor Madrid-Barcelona, y que Ouigo inicie sus operaciones en los corredores Madrid-Levante y Madrid-Andaluc\u00eda, lo que permitir\u00e1 afianzar el modelo actual.<\/p>\n<p>La liberalizaci\u00f3n del transporte de viajeros ha tenido un impacto positivo en el aumento de usuarios, llegando a superar las cifras anteriores a la crisis sanitaria en algunas conexiones. As\u00ed sucede con la relaci\u00f3n de alta velocidad Madrid-Barcelona, que en agosto super\u00f3 los 300.000 viajeros, por encima de los 265.000 usuarios del mismo mes de 2019, una tendencia que se ha consolidado en septiembre. Estas cifras ponen en valor el trabajo realizado, as\u00ed como la consolidaci\u00f3n de un modelo de sector bien asentado y que ha sabido reponerse de las adversidades, ha subrayado. \u201cEl transporte por ferrocarril no es el futuro, es el presente\u201d, ha afirmado.<\/p>\n<p><strong>Convenios con la Administraci\u00f3n General del Estado<\/strong><br \/>\nAsimismo, se ha referido a la firma de los convenios entre las dos entidades y la Administraci\u00f3n General del Estado (AGE) para la sostenibilidad de las infraestructuras ferroviarias durante el per\u00edodo 2021-2025, en virtud de los cuales Adif y Adif AV percibir\u00e1n 12.764 millones de euros. De este importe, Adif tiene asignados 8.747 millones de euros y Adif Alta Velocidad recibir\u00e1 4.017 millones de euros.<\/p>\n<p><strong>Bonificaciones para estimular la demanda<\/strong><br \/>\nEn lo que se refiere a los c\u00e1nones por utilizaci\u00f3n de las infraestructuras ferroviarias, Dom\u00ednguez ha destacado que la propuesta de tarifas para el pr\u00f3ximo ejercicio mantiene un sistema de bonificaciones para incentivar el aumento de las frecuencias actuales en los trenes de largo recorrido, que, seg\u00fan las l\u00edneas, puede llegar hasta el 50% del importe.<\/p>\n<p>Respecto a los c\u00e1nones de mercanc\u00edas, los importes por tren kil\u00f3metro permanecer\u00e1n en el mismo nivel que se ven\u00eda cobrando hasta este momento. Los importes propuestos en este \u00e1mbito seguir\u00e1n encontr\u00e1ndose entre los m\u00e1s bajos de Europa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta de ambas entidades ha presentado hoy sus presupuestos y l\u00edneas estrat\u00e9gicas en el Congreso de los Diputados \u2022<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[818],"tags":[71,986,1091,1377,1064],"class_list":["post-34435","post","type-post","status-publish","format-standard","hentry","category-notes-de-premsa","tag-adif","tag-alta-velocidad","tag-inversiones","tag-nuevas-lineas","tag-red-ferroviaria","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/34435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=34435"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/34435\/revisions"}],"predecessor-version":[{"id":34436,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/34435\/revisions\/34436"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=34435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=34435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=34435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}