{"id":31983,"date":"2020-11-24T19:04:35","date_gmt":"2020-11-24T17:04:35","guid":{"rendered":"https:\/\/www.agrupament.cat\/portal\/?p=31983"},"modified":"2020-11-24T19:31:51","modified_gmt":"2020-11-24T17:31:51","slug":"la-tecnologia-trainscanner-desarrollada-por-alstom-espan%cc%83a-entra-en-servicio-de-varsovia","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2020\/11\/la-tecnologia-trainscanner-desarrollada-por-alstom-espan%cc%83a-entra-en-servicio-de-varsovia\/","title":{"rendered":"La tecnolog\u00eda TrainScanner, desarrollada por Alstom Espa\u00f1a, entra en servicio de Varsovia"},"content":{"rendered":"<p>Se trata de una innovadora soluci\u00f3n de mantenimiento predictivo que utiliza c\u00e1maras 3D, tecnolog\u00eda l\u00e1ser y Big Data para evaluar el estado real de los equipos del tren.<\/p>\n<ul>\n<li><strong> La tecnolog\u00eda TrainScanner, desarrollada por Alstom Espa\u00f1a, entra en servicio de Varsovia<\/strong><\/li>\n<\/ul>\n<p>24 de noviembre de 2020 \u2013 TrainScanner, la soluci\u00f3n de mantenimiento predictivo desarrollada por los equipos de I+D de Alstom Espa\u00f1a, ha entrado en funcionamiento en el Centro de Mantenimiento de Varsovia, donde se utilizar\u00e1 para mantener la flota de 20 Avelia Pendolinos operada por PKP Intercity.<\/p>\n<p>La tecnolog\u00eda TrainScanner aporta un mantenimiento predictivo y una evaluaci\u00f3n continua de las condiciones t\u00e9cnicas del material rodante. Gracias al an\u00e1lisis digital de datos, identifica cu\u00e1l es el momento \u00f3ptimo para reemplazar un componente. El sistema implementado en Varsovia se basa en la larga experiencia de Alstom en Reino Unido, donde TrainScanner ha dado servicio a la flota Pendolino de Avanti West Coast durante a\u00f1os.<\/p>\n<p>\u00abTrainScanner se adelanta al futuro de la industria. Me alegra que los trenes de PKP Intercity sean revisados de esta manera tan innovadora, ya que no solo nos permitir\u00e1 ahorrar, sino que sobre todo nos permitir\u00e1 asegurar una mayor fiabilidad en nuestros trenes, as\u00ed como el confort y la seguridad de nuestros pasajeros\u00bb, ha enfatizado Adam Laskowski, miembro de la Junta de PKP Intercity S.A., el operador nacional de larga distancia cuya flota de material rodante incluye 20 trenes Pendolino de Alstom.<\/p>\n<p>A trav\u00e9s de c\u00e1maras 3D y tecnolog\u00eda l\u00e1ser, TrainScanner permite automatizar el mantenimiento predictivo y basado en la condici\u00f3n de las ruedas, las pastillas de freno y las bandas de carbono de pant\u00f3grafo, as\u00ed como de los bastidores y la carrocer\u00eda. Es especialmente adecuado para flotas numerosas, diseminadas o que requieran de un alto nivel de servicio, ya que el subsistema captura la informaci\u00f3n cuando el tren pasa a trav\u00e9s de TrainScanner. Tras la inspecci\u00f3n autom\u00e1tica, los datos se transmiten a la plataforma HealthHub de Alstom, que analiza los datos en bruto y los procesa a trav\u00e9s de algoritmos basados en reglas para calcular el buen estado de cada material.<\/p>\n<p>TrainScanner y HealthHub aportan beneficios notables en t\u00e9rminos tanto de mantenimiento como de operaci\u00f3n, ya que reducen tanto el consumo de materiales como el n\u00famero de operaciones de mantenimiento, otorgando un ahorro significativo a los propietarios y operadores de las flotas. El sistema prolonga el tiempo entre tareas de mantenimiento, alarga la vida de los componentes y mejora la seguridad durante la operaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de una innovadora soluci\u00f3n de mantenimiento predictivo que utiliza c\u00e1maras 3D, tecnolog\u00eda l\u00e1ser y Big Data para evaluar<\/p>\n","protected":false},"author":4,"featured_media":31984,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[818],"tags":[242,894,1109,610],"class_list":["post-31983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notes-de-premsa","tag-alstom","tag-mantenimiento-red","tag-trainscanner","tag-varsovia","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/31983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=31983"}],"version-history":[{"count":3,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/31983\/revisions"}],"predecessor-version":[{"id":31993,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/31983\/revisions\/31993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media\/31984"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=31983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=31983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=31983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}