{"id":24886,"date":"2017-04-13T07:59:42","date_gmt":"2017-04-13T06:59:42","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=24886"},"modified":"2017-04-13T07:59:42","modified_gmt":"2017-04-13T06:59:42","slug":"adif-saca-a-subasta-dos-viviendas-de-su-propiedad-en-jaca-huesca","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2017\/04\/adif-saca-a-subasta-dos-viviendas-de-su-propiedad-en-jaca-huesca\/","title":{"rendered":"Adif saca a subasta dos viviendas de su propiedad en Jaca (Huesca)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9682\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2011\/02\/Adif01.gif\" alt=\"\" width=\"83\" height=\"35\" \/>En el marco del plan de racionalizaci\u00f3n de activos de la entidad<br \/>\n\u00b7 Est\u00e1n situadas en la avenida Rapit\u00e1n, tienen 66 y 59 m2 de superficie y su precio de salida es de 41.800 y 40.545 euros, respectivamente.<\/p>\n<p>12\/04\/2017. Adif ha puesto a la venta, mediante subasta p\u00fablica, dos viviendas de su propiedad en el t\u00e9rmino municipal de Jaca (Huesca).<\/p>\n<p>Las dos viviendas est\u00e1n situadas en el n\u00famero 42 de la avenida Rapit\u00e1n de esta localidad, tienen 66 y 59 m2 \u00fatiles de superficie \u00fatil y disponen de 3 dormitorios, sal\u00f3n, cocina y un ba\u00f1o. El precio de salida es de 41.800 y 40.545 euros respectivamente.<\/p>\n<p>A las subastas p\u00fablicas pueden optar empresas y particulares a trav\u00e9s de la presentaci\u00f3n de las ofertas, cuyo plazo finaliza el pr\u00f3ximo 26 de abril, acompa\u00f1adas de la documentaci\u00f3n requerida y de la fianza establecida en las bases, que se pueden consultar en la p\u00e1gina web http:\/\/www.adif.es\/es_ES\/empresas_servicios\/concursos_publicos\/patrimonio\/concurso_publico_patrimonio_0176.shtml, as\u00ed como en la Delegaci\u00f3n de Patrimonio y Urbanismo de Adif en Zaragoza, a trav\u00e9s del tel\u00e9fono 976764539.<\/p>\n<p>Este concurso se inscribe en el plan de racionalizaci\u00f3n de activos que est\u00e1 llevando a cabo Adif, con el objetivo de mejorar la eficiencia en la gesti\u00f3n de estos activos, generar ingresos y reducir costes.<\/p>\n<p>Este plan incluye tres tipos de medidas: puesta en valor del patrimonio inmobiliario de la entidad que no forma parte sustancial e imprescindible para el desarrollo de su actividad, mediante su alquiler o venta; ofrecer a los actuales inquilinos de viviendas de titularidad de Adif pasar a ser propietarios, y optimizar el uso de los espacios y dependencias de car\u00e1cter interno.<\/p>\n<p>C\u00f3mo participar en las subastas<br \/>\nLas subastas realizadas por Adif se anuncian en prensa y en la p\u00e1gina web de la entidad, donde se pueden consultar los inmuebles que est\u00e1n a la venta en cada momento a trav\u00e9s del siguiente enlace: http:\/\/www.adif.es\/es_ES\/empresas_servicios\/concursos_publicos\/patrimonio\/concursos_patrimonio.shtml. Los inmuebles tambi\u00e9n se pueden visitar durante el plazo de presentaci\u00f3n de ofertas.<\/p>\n<p>Las ofertas deben efectuarse necesariamente por escrito, present\u00e1ndose en sobre cerrado la siguiente documentaci\u00f3n:<br \/>\n&#8211; Fotocopia del DNI.<br \/>\n&#8211; Declaraci\u00f3n firmada de que se cumplen los requisitos legales (se facilita modelo en el Pliego de Condiciones).<br \/>\n&#8211; Proposici\u00f3n econ\u00f3mica (seg\u00fan modelo que se facilita en el Pliego de Condiciones).<br \/>\n&#8211; Fianza mediante cheque nominativo o aval bancario.<\/p>\n<p>Una vez terminado el plazo de presentaci\u00f3n, se realizar\u00e1 una apertura p\u00fablica en donde se dar\u00e1n a conocer todas las ofertas recibidas. La adjudicaci\u00f3n recaer\u00e1 sobre la mayor oferta econ\u00f3mica, formaliz\u00e1ndose posteriormente la escritura de compraventa.<br \/>\n&#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del plan de racionalizaci\u00f3n de activos de la entidad \u00b7 Est\u00e1n situadas en la avenida Rapit\u00e1n, tienen<\/p>\n","protected":false},"author":4,"featured_media":24887,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[71,6,705],"class_list":["post-24886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-adif","tag-informacio-de-caracter-general","tag-jaca","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/24886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=24886"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/24886\/revisions"}],"predecessor-version":[{"id":24888,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/24886\/revisions\/24888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media\/24887"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=24886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=24886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=24886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}