{"id":23886,"date":"2016-12-03T11:54:00","date_gmt":"2016-12-03T10:54:00","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=23886"},"modified":"2016-12-03T11:54:00","modified_gmt":"2016-12-03T10:54:00","slug":"afectacions-al-servei-de-ll7-dfgc-per-obres-de-millora-de-laccessibilitat-del-putxet","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2016\/12\/afectacions-al-servei-de-ll7-dfgc-per-obres-de-millora-de-laccessibilitat-del-putxet\/","title":{"rendered":"Afectacions al servei de l&#8217;L7 d&#8217;FGC per obres de millora de l&#8217;accessibilitat del Putxet"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9662\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2011\/02\/TerritoriSostenibilitat.jpg\" alt=\"TerritoriSostenibilitat\" width=\"161\" height=\"35\" \/>02\/12\/2016. Des de dem\u00e0 i fins a l\u201911 de desembre els trens en direcci\u00f3 Pla\u00e7a Catalunya no s\u2019aturaran a l\u2019estaci\u00f3 del Putxet.<\/p>\n<p>L\u2019edicle de la pla\u00e7a de Joaquim Folguera estar\u00e0 tancat durant la interrupci\u00f3 de la circulaci\u00f3.<\/p>\n<p>Les obres de millora de l\u2019accessibilitat a l\u2019estaci\u00f3 d\u2019FGC del Putxet comportaran afectacions al servei de l\u2019L7 a partir de dem\u00e0, 3 de desembre, fins a l\u201911 de desembre. Durant aquest per\u00edode, els trens en direcci\u00f3 Pla\u00e7a Catalunya no s\u2019aturaran en aquesta estaci\u00f3 i l\u2019edicle de la pla\u00e7a Joaquim Folguera estar\u00e0 tancat.<\/p>\n<p>L\u2019alteraci\u00f3 al servei s\u2019iniciar\u00e0 a les 00,30 hores del 3 de desembre i finalitzaran a les 23,30 hores de l\u201911 de desembre. Estar\u00e0 en servei l\u2019andana en sentit Tibidabo i l\u2019acc\u00e9s del carrer Balmes. Cal recordar que el passad\u00eds que connecta les dues andanes est\u00e0 fora de servei.<\/p>\n<p>Els clients que vulguin viatjar en transport p\u00fablic des de Tibidabo fins al Putxet \u2013el trajecte a peu \u00e9s d\u2019uns cinc minuts\u2013 podran fer-ho en autob\u00fas (l\u00ednia V15 de TMB). Des del Putxet cap a qualsevol altra estaci\u00f3 d\u2019FGC, els usuaris poden dirigir-se a l\u2019estaci\u00f3 de P\u00e0dua, a peu (cinc minuts) o en autob\u00fas tamb\u00e9 amb la V15.<\/p>\n<p><strong>Inversi\u00f3 d\u20191,4 milions d\u2019euros<\/strong><br \/>\nDes del maig passat, estan en execuci\u00f3 les obres per adaptar l\u2019estaci\u00f3 del Putxet d\u2019FGC, que consisteixen en l\u2019ampliaci\u00f3 de l\u2019edicle de la pla\u00e7a de Joaquim Folguera per fer possible la instal\u00b7laci\u00f3 d\u2019un ascensor al seu interior. Aquest elevador connectar\u00e0 amb el pas existent sobre les vies i amb l&#8217;andana descendent i s\u2019instal\u00b7lar\u00e0 un segon ascensor per connectar l&#8217;altre extrem del pas superior amb l&#8217;andana ascendent. Les obres tenen un pressupost d\u20191,4 milions d\u2019euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>02\/12\/2016. Des de dem\u00e0 i fins a l\u201911 de desembre els trens en direcci\u00f3 Pla\u00e7a Catalunya no s\u2019aturaran a l\u2019estaci\u00f3<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[17,35,43,47,19,370],"class_list":["post-23886","post","type-post","status-publish","format-standard","hentry","tag-afectacions-e-incidencies","tag-barcelona","tag-estacions","tag-fgc-ferrocarrils-de-la-generalitat-de-catalunya","tag-infraestructures","tag-l07-barcelona-placa-catalunya-a-av-tibidabo","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/23886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=23886"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/23886\/revisions"}],"predecessor-version":[{"id":23887,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/23886\/revisions\/23887"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=23886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=23886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=23886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}