{"id":23097,"date":"2016-09-07T07:56:26","date_gmt":"2016-09-07T06:56:26","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=23097"},"modified":"2016-09-07T07:56:26","modified_gmt":"2016-09-07T06:56:26","slug":"adif-alta-velocidad-adjudica-las-obras-de-urbanizacion-del-parc-central-en-girona","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2016\/09\/adif-alta-velocidad-adjudica-las-obras-de-urbanizacion-del-parc-central-en-girona\/","title":{"rendered":"Adif Alta Velocidad adjudica las obras de urbanizaci\u00f3n del Parc Central en Girona"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-23098\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2016\/09\/ADIF-Alta-Velocidad.jpg\" alt=\"ADIF Alta Velocidad\" width=\"136\" height=\"50\" \/>\u2022 Se construir\u00e1 un parque p\u00fablico, se integrar\u00e1n las salidas de emergencia y se demoler\u00e1 la conexi\u00f3n actual entre los dos edificios de la estaci\u00f3n \u2022 La firma del convenio de colaboraci\u00f3n con el Ayuntamiento de Girona ha permitido agilizar los tr\u00e1mites necesarios para iniciar las obras en el menor plazo posible, de acuerdo con la voluntad manifestada por Adif Alta Velocidad<\/p>\n<p>06\/09\/2016. <strong><span style=\"color: #05362e;\"><a style=\"color: #05362e;\" href=\"http:\/\/www.adifaltavelocidad.es\/es_ES\/index.shtml\">Adif Alta Velocidad<\/a><\/span><\/strong> ha aprobado la adjudicaci\u00f3n de las obras de urbanizaci\u00f3n de la cubierta de la estaci\u00f3n de Girona de la L\u00ednea de Alta Velocidad Madrid-Barcelona-frontera francesa.<\/p>\n<p>El contrato ha sido adjudicado a la empresa <strong><span style=\"color: #000080;\"><a style=\"color: #000080;\" href=\"http:\/\/www.copcisa.com\">Construcciones y Obras P\u00fablicas y Civiles (Copcisa)<\/a><\/span><\/strong> por un importe de 1.690.285 euros (IVA incluido) y un plazo de ejecuci\u00f3n estimado de 5 meses.<\/p>\n<p>La firma del convenio de colaboraci\u00f3n con el Ayuntamiento de Girona ha posibilitado la aprobaci\u00f3n de la adjudicaci\u00f3n y la agilizaci\u00f3n de los tr\u00e1mites administrativos necesarios para poder iniciar los trabajos en el menor plazo posible, de acuerdo con la voluntad manifestada por Adif Alta Velocidad.<\/p>\n<p>En este sentido, la adjudicaci\u00f3n se ha aprobado en la primera reuni\u00f3n del Comit\u00e9 de Direcci\u00f3n de Adif Alta Velocidad que se ha celebrado tras la firma del convenio.<\/p>\n<p>Entre las principales actuaciones que Adif Alta Velocidad desarrollar\u00e1 en el sector del Parc Central, en un \u00e1mbito de 2,5 Ha entre las plazas de Joan Brossa y Europa, destaca la urbanizaci\u00f3n de la losa de cubierta de la estaci\u00f3n para su uso como parque p\u00fablico, la instalaci\u00f3n de salidas de emergencia a nivel de superficie y la demolici\u00f3n de la conexi\u00f3n actualmente existente entre los dos edificios de la estaci\u00f3n<\/p>\n<p>Tambi\u00e9n se ejecutar\u00e1 una nueva puerta de acceso, tanto al vest\u00edbulo del edificio de alta velocidad como al edificio de servicios de ancho convencional, y se dotar\u00e1 a las instalaciones de un sistema de repetidores de radiofrecuencia para emisores port\u00e1tiles utilizados por Protecci\u00f3n Civil y el departamento de Estaciones de Adif.<\/p>\n<p>El convenio firmado entre Adif Alta Velocidad y el Ayuntamiento contempla que este \u00faltimo financiar\u00e1 la demolici\u00f3n del finger y contratar\u00e1 y ejecutar\u00e1 una marquesina para sustituir este pasillo de conexi\u00f3n. Esta obra se llevar\u00e1 a cabo de forma coordinada con los trabajos que ejecutar\u00e1 Adif Alta Velocidad para garantizar que en todo momento los viajeros puedan hacer el recorrido entre los dos edificios a cubierto y resguardados de condiciones atmosf\u00e9ricas adversas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Se construir\u00e1 un parque p\u00fablico, se integrar\u00e1n las salidas de emergencia y se demoler\u00e1 la conexi\u00f3n actual entre los<\/p>\n","protected":false},"author":4,"featured_media":23099,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[71,41,43,34,19],"class_list":["post-23097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-adif","tag-ave","tag-estacions","tag-girona","tag-infraestructures","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/23097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=23097"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/23097\/revisions"}],"predecessor-version":[{"id":23100,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/23097\/revisions\/23100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media\/23099"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=23097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=23097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=23097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}