{"id":23006,"date":"2016-08-16T17:26:37","date_gmt":"2016-08-16T16:26:37","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=23006"},"modified":"2016-08-16T17:26:37","modified_gmt":"2016-08-16T16:26:37","slug":"caf-se-adjudica-contrato-de-suministro-de-10-unidades-para-metro-de-mexico","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2016\/08\/caf-se-adjudica-contrato-de-suministro-de-10-unidades-para-metro-de-mexico\/","title":{"rendered":"CAF SE ADJUDICA CONTRATO DE SUMINISTRO DE 10 UNIDADES PARA METRO DE MEXICO"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14788\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2012\/10\/CAF.jpg\" alt=\"CAF\" width=\"49\" height=\"50\" \/>16-08-2016. El <strong><span style=\"color: #aa14b5;\"><a style=\"color: #aa14b5;\" href=\"http:\/\/www.metro.cdmx.gob.mx\/organigrama\/despliegaOrganigrama.php?valor=0&amp;id_dir=294&amp;id_tipo=4\">Sistema de Transporte Colectivo, organismo dependiente del Gobierno del Distrito Federal<\/a><\/span><\/strong>, ha adjudicado a CAF M\u00e9xico, el contrato para el suministro de 10 trenes de rodadura neum\u00e1tica, para la L\u00ednea 1 del Metro de la Ciudad de M\u00e9xico. El contrato correspondiente tiene un valor aproximado de 164 millones de euros.<\/p>\n<p>Este contrato se engloba dentro del proyecto de renovaci\u00f3n de unidades e infraestructura que est\u00e1 llevando a cabo el Metro, estando planificada la entrega de las primeras unidades en el primer semestre del a\u00f1o 2018<\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"http:\/\/www.caf.net\/es\">CAF <\/a><\/span><\/strong>lleva desarrollando proyectos en M\u00e9xico desde el a\u00f1o 1992, y desde entonces ha suministrado un gran n\u00famero de unidades para varias l\u00edneas del Metro de la ciudad de M\u00e9xico, llevando a cabo de la misma forma diversos servicios de mantenimiento.<\/p>\n<p>Como resultado de esta intensa colaboraci\u00f3n con el Metro de la capital mexicana, cabe destacar que a finales del 2009, CAF result\u00f3 adjudicatario de un contrato que con una duraci\u00f3n de 15 a\u00f1os en la modalidad de PPS (Contrato de Prestaci\u00f3n por Servicios), y que inclu\u00eda adem\u00e1s del arrendamiento de 30 unidades para el Metro, el mantenimiento integral de los trenes durante dicho periodo.<\/p>\n<p>A ello, hay que a\u00f1adir el suministro y explotaci\u00f3n desde el a\u00f1o 2008, en r\u00e9gimen de concesi\u00f3n por un periodo de 50 a\u00f1os, del transporte ferroviario de pasajeros en la l\u00ednea del <strong><span style=\"color: #6b0b0b;\"><a style=\"color: #6b0b0b;\" href=\"http:\/\/www.fsuburbanos.com\/secciones\/espacio_viajero\/mapas.php\">suburbano, ruta Buenavista-Cuautitl\u00e1n, en la Ciudad de M\u00e9xico, D.F<\/a><\/span><\/strong>., as\u00ed como el proyecto de tren interurbano que actualmente est\u00e1 llevando a cabo, que unir\u00e1 la ciudad de M\u00e9xico con Toluca y que abarca el suministro de 30 unidades el\u00e9ctricas, as\u00ed como parte los sistemas de se\u00f1alizaci\u00f3n, participaci\u00f3n tambi\u00e9n en la ingenier\u00eda de integraci\u00f3n y de la coordinaci\u00f3n de este proyecto.<\/p>\n<p>De esta forma, con este nuevo contrato, CAF se sigue consolidando en el mercado mexicano, como el principal proveedor de trenes del Metro de la Ciudad de M\u00e9xico, de la misma forma que se confirma como uno de los proveedores m\u00e1s importantes de material ferroviario en el Continente Americano, donde ha desarrollado importantes proyectos en pa\u00edses como Estados Unidos, Brasil, Venezuela, Colombia, Ecuador y Chile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>16-08-2016. El Sistema de Transporte Colectivo, organismo dependiente del Gobierno del Distrito Federal, ha adjudicado a CAF M\u00e9xico, el contrato<\/p>\n","protected":false},"author":4,"featured_media":23007,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[78,19,225,318],"class_list":["post-23006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-caf","tag-infraestructures","tag-metro","tag-mexico","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/23006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=23006"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/23006\/revisions"}],"predecessor-version":[{"id":23008,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/23006\/revisions\/23008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media\/23007"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=23006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=23006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=23006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}