{"id":18901,"date":"2014-10-15T23:17:21","date_gmt":"2014-10-15T22:17:21","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=18901"},"modified":"2014-10-15T23:17:21","modified_gmt":"2014-10-15T22:17:21","slug":"pastor-anuncia-que-las-obras-del-nuevo-acceso-sur-viario-al-puerto-de-barcelona-comenzaran-en-las-proximas-semanas","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2014\/10\/pastor-anuncia-que-las-obras-del-nuevo-acceso-sur-viario-al-puerto-de-barcelona-comenzaran-en-las-proximas-semanas\/","title":{"rendered":"Pastor anuncia que las obras del nuevo  acceso sur viario al Puerto de Barcelona  comenzar\u00e1n en las pr\u00f3ximas semanas"},"content":{"rendered":"<p><strong><a href=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/09\/Fomento015.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8665\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2010\/09\/Fomento015.png\" alt=\"Fomento01\" width=\"130\" height=\"35\" \/><\/a>Tras reunise con el alcalde Barcelona<\/strong><\/p>\n<p>Madrid, 15 de octubre de 2014 (Ministerio de Fomento).<br \/>\nLa ministra de Fomento, Ana Pastor, ha adelantado hoy que las obras<br \/>\ndel nuevo acceso sur viario al Puerto de Barcelona comenzar\u00e1n en las<br \/>\npr\u00f3ximas semanas, una vez que se produzca la adjudicaci\u00f3n y<br \/>\nformalizaci\u00f3n del contrato.<\/p>\n<p>Tras reunirse con el alcalde de Barcelona, Xavier Tr\u00edas, la ministra ha<br \/>\nrecordado que la obra tiene un coste que supera los 100 millones de<br \/>\neuros. Tras aprobar el proyecto en julio de 2013, en enero de 2014 se<br \/>\nha licitado el contrato de obras y s\u00f3lo resta la adjudicaci\u00f3n de las<br \/>\nmismas para su inicio.<\/p>\n<p>En el encuentro con el alcalde Barcelona tambi\u00e9n se han abordado<br \/>\notros asuntos, seg\u00fan ha indicado la ministra, como el avance en las<br \/>\nobras de la estaci\u00f3n de La Sagrera y la licitaci\u00f3n del colector de Prim,<br \/>\nque se producir\u00e1 antes de fin de a\u00f1o para que las obras se puedan<br \/>\nadjudicar en 2015.<\/p>\n<p>Respecto a la estaci\u00f3n de Sants, ha indicado que el objetivo de ambas<br \/>\ninstituciones es dotar a la estaci\u00f3n de unas instalaciones de mejor<br \/>\ncalidad y que den mejor servicio a los ciudadanos.<\/p>\n<p>La ministra se ha referido tambi\u00e9n al proyecto de la Ronda Litoral, que<br \/>\npermitir\u00e1 compatibilizar \u201cla mejor explotaci\u00f3n ferroviaria y la mejor<br \/>\ncompetitividad del puerto de Barcelona\u201d, al tiempo que la terminal de El<br \/>\nMorrot contin\u00fae teniendo el espacio de explotaci\u00f3n necesario y de<br \/>\ncrecimiento y a la vez \u201chacer m\u00e1s ciudad\u201d.<\/p>\n<p>\u201cEl tema va muy avanzado y espero que en unos meses podamos<br \/>\npresentar este proyecto que creo que va a ser muy importante para el<br \/>\nfuturo de esta ciudad\u201d, ha agregado Pastor, quien ha insistido en que<br \/>\nse puede hacer compatible el puerto con la ciudad<\/p>\n<p>Pastor ha indicado que en la reuni\u00f3n se ha constatado que los<br \/>\nproyectos que tienen en marcha el Ministerio de Fomento y el<br \/>\nAyuntamiento de Barcelona \u201cvan avanzando a buen ritmo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras reunise con el alcalde Barcelona Madrid, 15 de octubre de 2014 (Ministerio de Fomento). La ministra de Fomento, Ana<\/p>\n","protected":false},"author":4,"featured_media":13969,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[35,305,333,381,43,19,69,2],"class_list":["post-18901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-barcelona","tag-barcelona-sants","tag-barcelona-sagrera-alta-velocitat","tag-centre-logistic-barcelona-morrot-can-tunis","tag-estacions","tag-infraestructures","tag-mitva-ministerio-de-fomento","tag-sant-andreu-districte","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/18901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=18901"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/18901\/revisions"}],"predecessor-version":[{"id":18902,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/18901\/revisions\/18902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media\/13969"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=18901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=18901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=18901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}