{"id":12265,"date":"2011-11-19T12:00:36","date_gmt":"2011-11-19T11:00:36","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=12265"},"modified":"2011-11-19T09:26:18","modified_gmt":"2011-11-19T08:26:18","slug":"en-el-centro-de-tecnologias-ferroviarias-de-malaga","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2011\/11\/en-el-centro-de-tecnologias-ferroviarias-de-malaga\/","title":{"rendered":"En el Centro de Tecnolog\u00edas Ferroviarias de M\u00e1laga"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9734\" title=\"Adif01\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2011\/02\/Adif011.gif\" alt=\"\" width=\"83\" height=\"35\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9906\" title=\"COMSA-EMTE\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2011\/03\/COMSA-EMTE1.jpg\" alt=\"\" width=\"69\" height=\"50\" \/>Adif y Comsa Emte suscriben un acuerdo marco para el desarrollo de actividades de investigaci\u00f3n y desarrollo tecnol\u00f3gico<br \/>\n<strong>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Comsa Emte instalar\u00e1 un laboratorio en el Centro de Tecnolog\u00edas Ferroviarias de Adif para el impulso de proyectos de alcance nacional e internacional en el \u00e1mbito ferroviario<\/strong><br \/>\n<strong>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Las l\u00edneas de investigaci\u00f3n prioritarias se articular\u00e1n en el \u00e1mbito de los nuevos materiales para plataformas ferroviarias, soluciones anti-vibratorias a partir de neum\u00e1ticos fuera de uso, l\u00ednea a\u00e9rea de contacto, sistemas de comunicaciones y\u00a0 eficiencia energ\u00e9tica en infraestructuras ferroviarias<\/strong><br \/>\n<strong>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Con esta nueva incorporaci\u00f3n, el Centro de Tecnolog\u00edas Ferroviarias de Adif cuenta ya con la presencia en sus instalaciones m\u00e1s de 20 empresas de vanguardia tecnol\u00f3gica<\/strong><br \/>\n<!--more--><\/p>\n<p>Madrid, 18 de noviembre de 2011 (Adif).<br \/>\nEl presidente de Adif, Antonio Gonz\u00e1lez Mar\u00edn, y Jorge Miarnau Montserrat, presidente de Comsa Emte, han suscrito un acuerdo marco de colaboraci\u00f3n en materia de investigaci\u00f3n y desarrollo tecnol\u00f3gico para la incorporaci\u00f3n de Comsa Emte al Centro de Tecnolog\u00edas Ferroviarias (CTF) de Adif en el Parque Tecnol\u00f3gico de Andaluc\u00eda (PTA) de M\u00e1laga.<\/p>\n<p>Con esta nueva incorporaci\u00f3n el Centro de Tecnolog\u00edas Ferroviarias de Adif ya cuenta en sus instalaciones con la presencia de m\u00e1s de 20\u00a0 empresas situadas en la vanguardia tecnol\u00f3gica con el objetivo de impulsar la I+D+i del sector ferroviario y apoyar la internacionalizaci\u00f3n de la tecnolog\u00eda espa\u00f1ola.<\/p>\n<p><strong>El acuerdo tiene como l\u00edneas de investigaci\u00f3n prioritarias los siguientes ejes:<\/strong><br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Estudios te\u00f3ricos y pr\u00e1cticos sobre las propiedades de nuevos materiales para la ejecuci\u00f3n de capas de forma y sub-balasto en plataformas ferroviarias.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Optimizaci\u00f3n de los sistemas de aislamiento ferroviario.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Desarrollo de soluciones anti-vibratorias a partir de neum\u00e1ticos fuera de uso.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Dise\u00f1o de nuevas soluciones para la prevenci\u00f3n de riesgos laborales en obras ferroviarias.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Investigaci\u00f3n de nuevas soluciones para la medici\u00f3n de referencias topogr\u00e1ficas de v\u00eda.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Recomendaciones para las tolerancias geom\u00e9tricas de v\u00eda en ferrocarriles urbanos.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Estudios de eficiencia energ\u00e9tica en infraestructuras ferroviarias.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Dise\u00f1o de soluciones avanzadas para la l\u00ednea a\u00e9rea de contacto.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Desarrollo de nuevos sistemas de comunicaciones.<\/p>\n<p><strong>Adem\u00e1s, el acuerdo marco suscrito entre Adif y Comsa Emte permitir\u00e1 el desarrollo de actividades de inter\u00e9s com\u00fan en el \u00e1mbito ferroviario, como son:<\/strong><br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La colaboraci\u00f3n en la creaci\u00f3n de consorcios p\u00fablico-privados para la presentaci\u00f3n de proyectos de I+D+i a convocatorias de ayudas nacionales y comunitarias, o para la presentaci\u00f3n de ofertas conjuntas a licitaciones internacionales.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La realizaci\u00f3n de estudios y la ejecuci\u00f3n de proyectos y programas de investigaci\u00f3n, desarrollo e innovaci\u00f3n en \u00e1reas cient\u00edficas de inter\u00e9s com\u00fan.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El asesoramiento rec\u00edproco, el apoyo mutuo y el intercambio de informaci\u00f3n en materias de fomento, desarrollo y seguimiento de actividades cient\u00edficas, mediante la elaboraci\u00f3n de informes, la creaci\u00f3n de grupos comunes de trabajo y otras formas de colaboraci\u00f3n.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La cooperaci\u00f3n en programas de formaci\u00f3n de personal investigador y t\u00e9cnico y el intercambio y colaboraci\u00f3n de personal, cuando la \u00edndole del trabajo com\u00fan as\u00ed lo requiera.<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Por otro lado, en virtud de este acuerdo marco, Adif pone a disposici\u00f3n de Comsa Emte una reserva de espacios en el CTF para la realizaci\u00f3n de actividades de colaboraci\u00f3n en temas cient\u00edfico-tecnol\u00f3gicos de inter\u00e9s com\u00fan.<\/p>\n<p><strong>El CTF de M\u00e1laga, un referente en innovaci\u00f3n tecnol\u00f3gica<\/strong><br \/>\nAdif, que ha apostado desde sus inicios por la innovaci\u00f3n y el desarrollo tecnol\u00f3gico, cuenta con 48 proyectos de I+D+i en fase de ejecuci\u00f3n y 6 proyectos recientemente aprobados en convocatoria INNPACTO 2011, todos ellos en colaboraci\u00f3n con distintos organismos, que representan una inversi\u00f3n global de 118 millones de euros, adem\u00e1s de la colaboraci\u00f3n que mantiene con m\u00e1s de 100 empresas espa\u00f1olas, 24 centros tecnol\u00f3gicos y 26 universidades.<\/p>\n<p>El Centro est\u00e1 concebido como un espacio abierto para impulsar la innovaci\u00f3n y la colaboraci\u00f3n empresarial enfocada al desarrollo tecnol\u00f3gico ferroviario a trav\u00e9s de proyectos de I+D+i.<\/p>\n<p>En la actualidad cuenta ya con la participaci\u00f3n y presencia de empresas de vanguardia tecnol\u00f3gica, adem\u00e1s de la propia Comsa Emte, como Abengoa, Acciona, Alcatel-Lucent, Azvi, Cetren, CIAC, Elecnor Deimos, Ferrovial, Huawei, Sando, Sice, Schneider, Ineco, Indra, Technosite, Thales, TJH2B, y Tria Railway; estando prevista la pr\u00f3xima incorporaci\u00f3n de nuevas organizaciones.\u00a0 De este modo, con la creaci\u00f3n del CTF Adif pretende reforzar el posicionamiento del sistema ferroviario espa\u00f1ol al frente de la vanguardia tecnol\u00f3gica europea y mundial. Este centro tecnol\u00f3gico y el anillo ferroviario complementario que se construir\u00e1 para ensayos estar\u00e1n a la vanguardia mundial de la investigaci\u00f3n, el desarrollo y la innovaci\u00f3n en el \u00e1mbito de la alta velocidad.<\/p>\n<p>El CTF cuenta en una primera fase con dos laboratorios especializados de Adif: el laboratorio GSM-R, para la tecnolog\u00eda de comunicaciones RBC-Tren y el desarrollo de ingenier\u00eda de datos para ERTMS, y el laboratorio TIC, dedicado a sistemas inteligentes de transporte y la evoluci\u00f3n del sistema DaVinci, sistema avanzado de gesti\u00f3n de tr\u00e1fico ferroviario.<\/p>\n<p>Adem\u00e1s, en el Centro se establecen departamentos especializados de formaci\u00f3n, vigilancia tecnol\u00f3gica, gesti\u00f3n de proyectos de I+D+i y transferencia tecnol\u00f3gica para el desarrollo de proyectos nacionales e internacionales propios de Adif, en cooperaci\u00f3n o incluso para terceros bajo contrato.<\/p>\n<p><strong>La I+D+i en Adif<\/strong><br \/>\nAdif tiene entre sus objetivos estrat\u00e9gicos el incremento de la cooperaci\u00f3n con entidades p\u00fablicas y privadas en actividades de investigaci\u00f3n, desarrollo e innovaci\u00f3n tecnol\u00f3gica dentro de sus potenciales \u00e1reas prioritarias de negocio y, asimismo, en proyectos de I+D+i promovidos por las administraciones p\u00fablicas espa\u00f1olas y de la Uni\u00f3n Europea a trav\u00e9s del Programa Marco de I+D+i.<br \/>\nEn este sentido, Adif ha creado en M\u00e1laga un Centro de Investigaci\u00f3n y Tecnolog\u00eda Ferroviaria y prev\u00e9 la construcci\u00f3n de instalaciones espec\u00edficas para el ensayo y la experimentaci\u00f3n (anillo ferroviario), como instalaci\u00f3n complementaria, que sirvan de referencia para el desarrollo de proyectos de I+D con los que incrementar la competitividad de las empresas nacionales y que, adem\u00e1s, contribuyan a posicionar el transporte ferroviario espa\u00f1ol al frente de la vanguardia tecnol\u00f3gica europea y mundial.<\/p>\n<p><strong>Comsa Emte<\/strong><br \/>\nComsa Emte es el segundo grupo espa\u00f1ol no cotizado en el sector de las infraestructuras, servicios, ingenier\u00eda y sistemas. El grupo empresarial cuenta con una presencia permanente en 15 pa\u00edses y una plantilla superior a las 9.500 personas.<br \/>\nComsa Emte participa en el desarrollo de las infraestructuras ferroviarias espa\u00f1olas desde 1891 y ofrece un servicio integral en el \u00e1mbito del ferrocarril que abarca desde el estudio inicial y el proyecto, a la construcci\u00f3n y el mantenimiento de infraestructuras, superestructuras e instalaciones ferroviarias tanto de alta velocidad como convencionales, desarrollando y mejorando entre otros, sistemas de transporte colectivo de m\u00faltiples ciudades a nivel mundial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adif y Comsa Emte suscriben un acuerdo marco para el desarrollo de actividades de investigaci\u00f3n y desarrollo tecnol\u00f3gico \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Comsa<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[71,80,37,19,94],"class_list":["post-12265","post","type-post","status-publish","format-standard","hentry","tag-adif","tag-comsaemte","tag-espana","tag-infraestructures","tag-malaga","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/12265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=12265"}],"version-history":[{"count":5,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/12265\/revisions"}],"predecessor-version":[{"id":12270,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/12265\/revisions\/12270"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=12265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=12265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=12265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}