{"id":10653,"date":"2011-05-11T20:40:10","date_gmt":"2011-05-11T19:40:10","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=10653"},"modified":"2011-05-11T20:40:10","modified_gmt":"2011-05-11T19:40:10","slug":"cataluna-es-la-primera-comunidad-en-inversion-ejecutada-por-el-ministerio-de-fomento-con-unos-15-000-me-desde-2004","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2011\/05\/cataluna-es-la-primera-comunidad-en-inversion-ejecutada-por-el-ministerio-de-fomento-con-unos-15-000-me-desde-2004\/","title":{"rendered":"Catalu\u00f1a es la primera comunidad en inversi\u00f3n ejecutada por el Ministerio de Fomento, con unos 15.000 M\u20ac desde 2004"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9709\" title=\"Fomento01\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2011\/02\/Fomento01.png\" alt=\"\" width=\"130\" height=\"35\" \/>\u2022 En los \u00faltimos 7 a\u00f1os el Gobierno ha invertido en Cercan\u00edas de Catalu\u00f1a m\u00e1s de 1.000 M\u20ac<\/strong><br \/>\n<!--more--><br \/>\nMadrid, 11 de mayo de 2011 (Ministerio de Fomento).<br \/>\nEl Ministerio de Fomento ha ejecutado desde 2004 inversiones en infraestructuras por un importe de unos 15.000 M\u20ac en Catalu\u00f1a. Ha sido \u201cel mayor periodo de inversi\u00f3n en infraestructuras estatales de la historia de esta comunidad aut\u00f3noma\u201d, seg\u00fan manifest\u00f3 hoy la secretaria general de Infraestructuras, Inmaculada Rodr\u00edguez Pi\u00f1ero.<\/p>\n<p>De hecho, a d\u00eda de hoy Catalu\u00f1a es la primera comunidad en inversi\u00f3n ejecutada por Fomento. Rodr\u00edguez Pi\u00f1ero se\u00f1al\u00f3, adem\u00e1s, que desde la aprobaci\u00f3n del Estatut de Autonom\u00eda en 2006, la inversi\u00f3n real ejecutada se sit\u00faa al nivel de la participaci\u00f3n de Catalu\u00f1a en el PIB.<\/p>\n<p>Ejemplo de esta apuesta por Catalu\u00f1a ha sido la inversi\u00f3n realizada en Cercan\u00edas desde 2004, que ha superado los 1.000 M\u20ac, \u201clo que significa multiplicar la inversi\u00f3n por m\u00e1s de 3 con respecto al Gobierno anterior\u201d, indic\u00f3 la secretaria general.<\/p>\n<p>En relaci\u00f3n a las declaraciones realizadas hoy por el conseller de Territorio de la Generalitat de Catalu\u00f1a, Lluis Recoder, la Secretaria General ha se\u00f1alado \u201cque todos estamos de acuerdo en la necesidad de mejorar las Rodalies, y espero que tambi\u00e9n lo estemos en que la ejecuci\u00f3n de las obras se deben ajustar a la capacidad de financiaci\u00f3n. No se puede invertir lo que no se puede pagar.\u201d<\/p>\n<p>En cualquier caso, Rodr\u00edguez Pi\u00f1ero cree necesario \u201cdesmarcar este tipo de pol\u00e9mica del periodo electoral en el que nos encontramos, para evitar la utilizaci\u00f3n de este tipo de temas con fines electoralistas\u201d.<\/p>\n<p>La secretaria general de Infraestructuras considera que \u201cCatalu\u00f1a necesita el esfuerzo y la coordinaci\u00f3n de ambas Administraciones para que disfrute de las Rodalies que necesita, pero no se puede exigir, y menos en las circunstancias actuales, que un Plan de Actuaci\u00f3n que finaliza en 2015 est\u00e9 ejecutado en 2011\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 En los \u00faltimos 7 a\u00f1os el Gobierno ha invertido en Cercan\u00edas de Catalu\u00f1a m\u00e1s de 1.000 M\u20ac<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[36,37,6,19,44],"class_list":["post-10653","post","type-post","status-publish","format-standard","hentry","tag-catalunya","tag-espana","tag-informacio-de-caracter-general","tag-infraestructures","tag-rodalies-cercanias","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/10653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=10653"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/10653\/revisions"}],"predecessor-version":[{"id":10654,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/10653\/revisions\/10654"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=10653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=10653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=10653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}