{"id":10116,"date":"2011-03-22T18:34:51","date_gmt":"2011-03-22T17:34:51","guid":{"rendered":"http:\/\/www.agrupament.cat\/portal\/?p=10116"},"modified":"2011-03-22T18:34:51","modified_gmt":"2011-03-22T17:34:51","slug":"adif-y-el-ayuntamiento-de-montcada-i-reixac-promueven-la-integracion-urbanistica-de-las-infraestructuras-ferroviarias-en-el-barrio-de-can-sant-joan","status":"publish","type":"post","link":"https:\/\/www.agrupament.cat\/portal\/2011\/03\/adif-y-el-ayuntamiento-de-montcada-i-reixac-promueven-la-integracion-urbanistica-de-las-infraestructuras-ferroviarias-en-el-barrio-de-can-sant-joan\/","title":{"rendered":"Adif y el Ayuntamiento de Montcada i Reixac promueven la integraci\u00f3n urban\u00edstica de las infraestructuras ferroviarias en el barrio de Can Sant Joan"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9734\" title=\"Adif01\" src=\"http:\/\/www.agrupament.cat\/portal\/wp-content\/uploads\/2011\/02\/Adif011.gif\" alt=\"\" width=\"83\" height=\"35\" \/>El convenio de colaboraci\u00f3n ha sido firmado hoy en Barcelona<\/p>\n<p><strong>Esta actuaci\u00f3n contempla la construcci\u00f3n de un aparcamiento p\u00fablico con capacidad para 100 veh\u00edculos y 20 motocicletas en la pla\u00e7a de la Pedra<\/strong><br \/>\n<strong>Adem\u00e1s, se crear\u00e1 una pantalla vegetal y una zona arbolada en el entorno del complejo de Montcada Bifurcaci\u00f3 <\/strong><br \/>\n<!--more--><\/p>\n<p>Barcelona, 22 de marzo de 2011 (Adif).<br \/>\nEl presidente de Adif, Antonio Gonz\u00e1lez Mar\u00edn, y la alcaldesa de Montcada i Reixac, Mar\u00eda Elena P\u00e9rez, han firmado hoy en la sede de la Delegaci\u00f3n del Gobierno en Catalunya un convenio de colaboraci\u00f3n para promover la integraci\u00f3n urban\u00edstica de las infraestructuras ferroviarias en el barrio de Can Sant Joan.<\/p>\n<p>Las actuaciones m\u00e1s destacadas recogidas en este acuerdo consistir\u00e1n en la construcci\u00f3n de un aparcamiento p\u00fablico con capacidad para 100 veh\u00edculos y 20 motocicletas en la pla\u00e7a de la Pedra, y la creaci\u00f3n de una pantalla vegetal y una zona arbolada en el entorno del complejo ferroviario de Montcada Bifurcaci\u00f3.<\/p>\n<p>La firma de este acuerdo es fruto de las reuniones mantenidas entre Adif y el Ayuntamiento para minimizar el impacto de la construcci\u00f3n de nuevas instalaciones de mantenimiento de infraestructura en el complejo de Montcada Bifurcaci\u00f3, as\u00ed como para facilitar su integraci\u00f3n y mejorar el acceso a la estaci\u00f3n de ferrocarril.<\/p>\n<p>Estos equipamientos se han desplazado desde su antiguo emplazamiento, en el tri\u00e1ngulo ferroviario de Sant Andreu Comtal, con motivo de la construcci\u00f3n de nuevas infraestructuras en este sector de Barcelona, tanto de la L\u00ednea de Alta Velocidad como de la de ancho convencional.<\/p>\n<p>Asimismo, el convenio, que se enmarca en la pol\u00edtica de responsabilidad social corporativa de Adif, tiene entre sus objetivos la mejora de la inserci\u00f3n de las infraestructuras en el medio urbano, en concertaci\u00f3n con las dem\u00e1s administraciones, con la doble finalidad de articularlas en el sistema de transporte de las ciudades y contribuir a la regeneraci\u00f3n del espacio urbano.<\/p>\n<p>Actuaciones a desarrollar<br \/>\nSeg\u00fan las estipulaciones del convenio, Adif elaborar\u00e1 un proyecto y ejecutar\u00e1 las obras de construcci\u00f3n de un aparcamiento p\u00fablico que dar\u00e1 servicio a los clientes del ferrocarril y a los vecinos del barrio de Can Sant Joan. Situado en la pla\u00e7a de la Pedra, tendr\u00e1 capacidad para 100 veh\u00edculos y 20 motocicletas. Ambas partes suscribir\u00e1n un convenio para el desarrollo del acuerdo firmado hoy en el que se concretar\u00e1n los t\u00e9rminos de utilizaci\u00f3n del nuevo aparcamiento.<\/p>\n<p>Adif tambi\u00e9n llevar\u00e1 a cabo los trabajos de tratamiento paisaj\u00edstico en el entorno del complejo de Montcada Bifurcaci\u00f3, mediante la creaci\u00f3n de una pantalla vegetal y una zona arbolada en el talud colindante con la calle Bifurcaci\u00f3n, sobre el que se levantan las nuevas instalaciones ferroviarias.<\/p>\n<p>Por su parte, el Ayuntamiento, que asumir\u00e1 el mantenimiento y conservaci\u00f3n de esta nueva zona verde, se obliga a dar a conocer la contribuci\u00f3n de Adif a la recuperaci\u00f3n paisaj\u00edstica a trav\u00e9s de paneles y contenidos informativos espec\u00edficos.<\/p>\n<p>Por otro lado, seg\u00fan el convenio, ambas partes estudiar\u00e1n la viabilidad y oportunidad de que, tras una modificaci\u00f3n del planeamiento vigente, se califique una parcela como zona verde para su desafecci\u00f3n del servicio ferroviario con el fin de atribuirle el correspondiente aprovechamiento urban\u00edstico por parte del Ayuntamiento.<br \/>\nAdem\u00e1s, se estudiar\u00e1n conjuntamente las f\u00f3rmulas para que, en ejecuci\u00f3n del planeamiento vigente, el Ayuntamiento obtenga suelos de titularidad de Adif adyacentes a los terrenos ferroviarios, actualmente ocupados por viales p\u00fablicos, taludes y espacios verdes en las calles Bifurcaci\u00f3n, Vinyes y Bater\u00eda, y en las plazas de la Pedra y Sant Joan.<\/p>\n<p>El convenio tambi\u00e9n estipula la creaci\u00f3n de una comisi\u00f3n de seguimiento, formada por dos representantes de cada organismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El convenio de colaboraci\u00f3n ha sido firmado hoy en Barcelona Esta actuaci\u00f3n contempla la construcci\u00f3n de un aparcamiento p\u00fablico con<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[35,43,44],"class_list":["post-10116","post","type-post","status-publish","format-standard","hentry","tag-barcelona","tag-estacions","tag-rodalies-cercanias","comments-off"],"_links":{"self":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/10116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/comments?post=10116"}],"version-history":[{"count":1,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/10116\/revisions"}],"predecessor-version":[{"id":10117,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/posts\/10116\/revisions\/10117"}],"wp:attachment":[{"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/media?parent=10116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/categories?post=10116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrupament.cat\/portal\/wp-json\/wp\/v2\/tags?post=10116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}